{"id":96116,"date":"2022-06-26T10:20:09","date_gmt":"2022-06-26T14:20:09","guid":{"rendered":"https:\/\/www.cuballama.com\/noticias\/?p=96116"},"modified":"2022-06-26T10:20:13","modified_gmt":"2022-06-26T14:20:13","slug":"cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada","status":"publish","type":"post","link":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/","title":{"rendered":"Cayo Largo del Sur ser\u00e1 de Sunwing, Blue Diamond y Canad\u00e1"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">No va a ser f\u00e1cil reflotar en el mapa tur\u00edstico cubano a este hermoso islote de Cayo Largo del Sur, condenado, entre otras cosas, por no tener conexi\u00f3n v\u00eda terrestre con la isla de Cuba. <\/h2>\n\n\n\n<p>Blue Diamond Resorts de Sunwing Travel Group ser\u00e1 responsable de administrar los once hoteles existentes en Cayo Largo del Sur, un islote tur\u00edstico inaugurado en el a\u00f1o 1981 frente a la costa sur de Cuba y que, durante 40 a\u00f1os pas\u00f3, de tener decenas de vuelos semanales, procedentes de pa\u00edses como Inglaterra, Argentina, Italia, Alemania y Canad\u00e1, a recibir solo, pr\u00e1cticamente, turistas canadienses.<\/p>\n\n\n\n<p>Durante cuarenta a\u00f1os, entre mosquitos perennes e incomunicaci\u00f3n terrestre con la isla mayor, Cuba, que acrecentaban semana tras semanas los problemas de abastecimiento al cayo, nunca lleg\u00f3 el a\u00f1orado despegue tur\u00edstico del islote, ese que ahora, tras culminar el evento \u00abSunwing Loves Cuba\u00bb, espera renacer como el Ave F\u00e9nix.<\/p>\n\n\n\n<p>Lo curioso es que lo har\u00e1 &#8211; o lo intentar\u00e1 &#8211; con Sunwing, una agencia que hace diez a\u00f1os apenas si ten\u00eda turistas en Cayo Largo del Sur, y que opera un segmento muy distinto a la de la tradicional y pr\u00e1cticamente due\u00f1a de todos los vuelos procedentes desde Canad\u00e1, Air Transat.<\/p>\n\n\n\n<p>El acuerdo durar\u00e1 diez a\u00f1os, y durante ese tiempo, Blue Diamond operar\u00e1 un total de 1,348 habitaciones. La cadena se ha convertido r\u00e1pidamente en el segundo grupo hotelero m\u00e1s grande de la isla, solo por detr\u00e1s de la espa\u00f1ola Meli\u00e1. Cuba, adem\u00e1s, es es el destino m\u00e1s grande de Sunwing, y Sunwing es la fuente de turistas m\u00e1s grande de Cuba.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n-1024x768.jpg\" alt=\"\" class=\"wp-image-96123\" srcset=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n-1024x768.jpg 1024w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n-300x225.jpg 300w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n-768x576.jpg 768w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n-1536x1152.jpg 1536w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n-150x113.jpg 150w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n-696x522.jpg 696w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n-1068x801.jpg 1068w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n-1920x1440.jpg 1920w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n-80x60.jpg 80w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n-265x198.jpg 265w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130818\/274183943_1934638250076452_6843347122707385700_n.jpg 1984w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Uno de los grandes atractivos de Cayo Largo del Sur es la visita a Cayo Iguana, donde cientos de estos animales viven y se reproducen en un entorno natural y hasta amigable con los seres humanos que los visitan. Foto: <a href=\"https:\/\/www.facebook.com\/groups\/1519990288296053\/user\/100005908876529\/?__cft__[0]=AZW9AUyjlCSnz5id8y-U_3FmjRIlutooqp2XIUC1q9Xn2phApFjUHjraSHVEZdVQinsEkVZUoJD-G3Uib4J_IkMmxr6xSBXnoqPLbPhTcq8DTfFwccx8q9he-oy4a5V2vQsGycwXePRVbCQzCY7-AfZ4&amp;__tn__=-UC*F\">Slavek Stepczynski<\/a><\/figcaption><\/figure>\n\n\n\n<p>Con tan \u00abbuenos referentes\u00bb, se esperar\u00eda empero un producto de alta calidad y eso es lo que nunca ha podido ofrecer Cayo Largo del Sur, donde excepto un par de honrosas excepciones, todos sus directivos hoteleros, gerentes y managers, m\u00e1s que capacitados en hoteler\u00eda son miembros del Partido Comunista de Cuba, y responden a los intereses pol\u00edticos del gobierno.<\/p>\n\n\n\n<p>El acuerdo entre ambos grupos se hizo p\u00fablico en mayo, pero el evento y la firma se celebr\u00f3 ayer en Toronto. <\/p>\n\n\n\n<p>La \u00fanica verdad, si acaso, expresada por el vicepresidente ejecutivo de asociaciones estrat\u00e9gicas de Sunwing, Eric Rodr\u00edguez y por el director general de Blue Diamond Resorts, Mohamad Fawzi, cuando se les pregunt\u00f3 sobre la oportunidad que representa Cayo Largo del Sur para Sunwing, es que Cayo Largo \u00abes un gran destino, muy conocido en Quebec\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"355\" src=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130159\/630x355-4.jpg\" alt=\"\" class=\"wp-image-96122\" srcset=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130159\/630x355-4.jpg 630w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130159\/630x355-4-300x169.jpg 300w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24130159\/630x355-4-150x85.jpg 150w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><figcaption>Eric Rodr\u00edguez, vicepresidente ejecutivo de asociaciones estrat\u00e9gicas de Sunwing Eric Rodr\u00edguez y el director general de Blue Diamond Resorts, Mohamad Fawzi. Foto: TravelPulse.ca<\/figcaption><\/figure>\n\n\n\n<p>Los ejecutivos dijeron que est\u00e1n interesados en \u00abvolver a poner a Cayo Largo en el mapa (tur\u00edstico)\u00bb, una frase que evidencia cuan alejado est\u00e1 Cayo Largo del Sur de sus d\u00edas de gloria.<\/p>\n\n\n\n<p>La mejor noticia del evento fue el anuncio hecho por Mohamad Fawzi, quien se\u00f1al\u00f3 en <strong><a href=\"https:\/\/ca.travelpulse.com\/news\/tour-operators\/sunwing-loves-cuba-event-reveals-more-details-on-big-cayo-largo-deal.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">entrevista a la revista TravelPulse <\/a><\/strong>que Blue Diamond planea construir una propiedad Royalton de 250 habitaciones en Cayo Largo, con una fecha de apertura de 2025-2026, una noticia muy similar a la que corri\u00f3 en boca de todos los trabajadores y directivos de Cayo Largo del Sur, cuando cierto Jeque \u00c1rabe, multimillonario, visit\u00f3 Cayo Largo del Sur, conoci\u00f3 Playa Para\u00edso y dijo que pondr\u00eda todo el dinero necesario para construir all\u00ed, frente o bien cerquita de la playa, el mayor hotel de Cayo Largo del Sur, algo que nunca se concret\u00f3, no se sabe si porque la frase fue dicha tras una borrachera, una ingesta de langosta o porque al Grupo Gran Caribe, al MINTUR o al gobierno cubano, no les interes\u00f3 el acuerdo con \u00abel jeque\u00bb.<\/p>\n\n\n\n<p>Como noticia trascendental tambi\u00e9n trascendi\u00f3 que los hoteles existentes se renombrar\u00e1n con banderas Blue Diamond, incluidos Grand Memories, Sanctuary at Grand Memories, Memories y Starfish.<\/p>\n\n\n\n<p>Es decir, que ya no ser\u00e1n \u00abPel\u00edcano\u00bb, \u00abIsla del Sur\u00bb, \u00abIguana\u00bb o \u00abLindamar\u00bb, sino que tendr\u00e1n otros nombres.<\/p>\n\n\n\n<p>Empero, la mejor noticia tal vez llegue para sus trabajadores, que cansados de trabajar durante 20 d\u00edas consecutivos en turnos diarios de doce horas, para turistas que no dan propina, recibir\u00e1n a los canadienses, los \u00fanicos turistas que, durante d\u00e9cadas han sido los que tradicionalmente han contentado los empobrecidos bolsillos de los trabajadores del bell\u00edsimo islote.<\/p>\n\n\n\n<p><strong>tal vez quieras leer: <a href=\"https:\/\/www.cuballama.com\/noticias\/se-refugian-en-cuba-millonarios-rusos-con-sus-yates\/\">\u00bfSe refugian en Cuba millonarios rusos con sus yates?<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blue Diamond Resorts de Sunwing Travel Group ser\u00e1 responsable de administrar los once hoteles existentes en Cayo Largo del Sur, un islote tur\u00edstico inaugurado en el a\u00f1o 1981 frente a la costa sur de Cuba y que, durante 40 a\u00f1os pas\u00f3, de tener decenas de vuelos semanales, procedentes de pa\u00edses como Inglaterra, Argentina, Italia, Alemania y Canad\u00e1, a recibir solo, pr\u00e1cticamente, turistas canadienses.<\/p>\n","protected":false},"author":13,"featured_media":96124,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[955],"tags":[11673,3450,941,499],"class_list":{"0":"post-96116","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-de-cuba","8":"tag-blue-diamond-resorts","9":"tag-cayo-largo-del-sur","10":"tag-destacado","11":"tag-turismo-en-cuba"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cayo Largo del Sur ser\u00e1 de Sunwing, Blue Diamond y Canad\u00e1 - Cuballama Noticias<\/title>\n<meta name=\"description\" content=\"Cayo Largo del Sur: el islote m\u00e1s bello que se pueda conocer en Cuba. Tras 40 a\u00f1os, Sunwing y Blue Diamond apuestan por reflotarlo en el mapa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cayo Largo del Sur ser\u00e1 de Sunwing, Blue Diamond y Canad\u00e1 - Cuballama Noticias\" \/>\n<meta property=\"og:description\" content=\"Cayo Largo del Sur: el islote m\u00e1s bello que se pueda conocer en Cuba. Tras 40 a\u00f1os, Sunwing y Blue Diamond apuestan por reflotarlo en el mapa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuballama Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CubaLlama\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-26T14:20:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-26T14:20:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuballama.com\/noticias\/wp-content\/uploads\/2022\/06\/PLaya-Sirena.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberto A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuballama\" \/>\n<meta name=\"twitter:site\" content=\"@cuballama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/\"},\"author\":{\"name\":\"Roberto A.\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/a58502ed4146c8e9f83872e897c76cd2\"},\"headline\":\"Cayo Largo del Sur ser\u00e1 de Sunwing, Blue Diamond y Canad\u00e1\",\"datePublished\":\"2022-06-26T14:20:09+00:00\",\"dateModified\":\"2022-06-26T14:20:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/\"},\"wordCount\":805,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/24131603\\\/PLaya-Sirena.jpg\",\"keywords\":[\"Blue Diamond Resorts\",\"Cayo Largo del Sur\",\"destacado\",\"Turismo en Cuba\"],\"articleSection\":[\"Noticias de Cuba\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/\",\"name\":\"Cayo Largo del Sur ser\u00e1 de Sunwing, Blue Diamond y Canad\u00e1 - Cuballama Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/24131603\\\/PLaya-Sirena.jpg\",\"datePublished\":\"2022-06-26T14:20:09+00:00\",\"dateModified\":\"2022-06-26T14:20:13+00:00\",\"description\":\"Cayo Largo del Sur: el islote m\u00e1s bello que se pueda conocer en Cuba. Tras 40 a\u00f1os, Sunwing y Blue Diamond apuestan por reflotarlo en el mapa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/24131603\\\/PLaya-Sirena.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/24131603\\\/PLaya-Sirena.jpg\",\"width\":2048,\"height\":1536,\"caption\":\"Playa Sirena, al menos 200 kil\u00f3metros de ancho de franja de arena, y luego un mar muy azul. La playa, junto a Playa Para\u00edso, es lo mejor de Cayo Largo del Sur. Foto: Angel Andr\u00e9s Leyva \\\/ Facebook\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cayo Largo del Sur ser\u00e1 de Sunwing, Blue Diamond y Canad\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"name\":\"Cuballama Noticias\",\"description\":\"Medio digital sobre Cuba y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\",\"name\":\"Cuballama\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"width\":600,\"height\":133,\"caption\":\"Cuballama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CubaLlama\",\"https:\\\/\\\/x.com\\\/cuballama\",\"https:\\\/\\\/www.instagram.com\\\/stories\\\/cuballama_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKkFE-d_axENGZcrc4as0IA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/a58502ed4146c8e9f83872e897c76cd2\",\"name\":\"Roberto A.\",\"description\":\"Roberto A. Periodista por decisi\u00f3n propia. Interesado en cualquier tema que me apasione y cada vez m\u00e1s comprometido con la verdad y la objetividad period\u00edstica. Graduado en La Habana hace ya muchos a\u00f1os, luego de una accidentada y polvorienta b\u00fasqueda de informaci\u00f3n sobre un tema in\u00e9dito. La Tesis, por cierto, desapareci\u00f3 de la biblioteca y no se conservan copias de la misma.\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/author\\\/roberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cayo Largo del Sur ser\u00e1 de Sunwing, Blue Diamond y Canad\u00e1 - Cuballama Noticias","description":"Cayo Largo del Sur: el islote m\u00e1s bello que se pueda conocer en Cuba. Tras 40 a\u00f1os, Sunwing y Blue Diamond apuestan por reflotarlo en el mapa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/","og_locale":"es_ES","og_type":"article","og_title":"Cayo Largo del Sur ser\u00e1 de Sunwing, Blue Diamond y Canad\u00e1 - Cuballama Noticias","og_description":"Cayo Largo del Sur: el islote m\u00e1s bello que se pueda conocer en Cuba. Tras 40 a\u00f1os, Sunwing y Blue Diamond apuestan por reflotarlo en el mapa","og_url":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/","og_site_name":"Cuballama Noticias","article_publisher":"https:\/\/www.facebook.com\/CubaLlama","article_published_time":"2022-06-26T14:20:09+00:00","article_modified_time":"2022-06-26T14:20:13+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.cuballama.com\/noticias\/wp-content\/uploads\/2022\/06\/PLaya-Sirena.jpg","type":"image\/jpeg"}],"author":"Roberto A.","twitter_card":"summary_large_image","twitter_creator":"@cuballama","twitter_site":"@cuballama","twitter_misc":{"Escrito por":"Roberto A.","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/#article","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/"},"author":{"name":"Roberto A.","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/a58502ed4146c8e9f83872e897c76cd2"},"headline":"Cayo Largo del Sur ser\u00e1 de Sunwing, Blue Diamond y Canad\u00e1","datePublished":"2022-06-26T14:20:09+00:00","dateModified":"2022-06-26T14:20:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/"},"wordCount":805,"publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24131603\/PLaya-Sirena.jpg","keywords":["Blue Diamond Resorts","Cayo Largo del Sur","destacado","Turismo en Cuba"],"articleSection":["Noticias de Cuba"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/","url":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/","name":"Cayo Largo del Sur ser\u00e1 de Sunwing, Blue Diamond y Canad\u00e1 - Cuballama Noticias","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/#primaryimage"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24131603\/PLaya-Sirena.jpg","datePublished":"2022-06-26T14:20:09+00:00","dateModified":"2022-06-26T14:20:13+00:00","description":"Cayo Largo del Sur: el islote m\u00e1s bello que se pueda conocer en Cuba. Tras 40 a\u00f1os, Sunwing y Blue Diamond apuestan por reflotarlo en el mapa","breadcrumb":{"@id":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/#primaryimage","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24131603\/PLaya-Sirena.jpg","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/06\/24131603\/PLaya-Sirena.jpg","width":2048,"height":1536,"caption":"Playa Sirena, al menos 200 kil\u00f3metros de ancho de franja de arena, y luego un mar muy azul. La playa, junto a Playa Para\u00edso, es lo mejor de Cayo Largo del Sur. Foto: Angel Andr\u00e9s Leyva \/ Facebook"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuballama.com\/noticias\/cayo-largo-del-sur-sera-de-sunwing-blue-diamond-y-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cuballama.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Cayo Largo del Sur ser\u00e1 de Sunwing, Blue Diamond y Canad\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/www.cuballama.com\/noticias\/#website","url":"https:\/\/www.cuballama.com\/noticias\/","name":"Cuballama Noticias","description":"Medio digital sobre Cuba y el mundo","publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuballama.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cuballama.com\/noticias\/#organization","name":"Cuballama","url":"https:\/\/www.cuballama.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","width":600,"height":133,"caption":"Cuballama"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CubaLlama","https:\/\/x.com\/cuballama","https:\/\/www.instagram.com\/stories\/cuballama_oficial\/","https:\/\/www.youtube.com\/channel\/UCKkFE-d_axENGZcrc4as0IA"]},{"@type":"Person","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/a58502ed4146c8e9f83872e897c76cd2","name":"Roberto A.","description":"Roberto A. Periodista por decisi\u00f3n propia. Interesado en cualquier tema que me apasione y cada vez m\u00e1s comprometido con la verdad y la objetividad period\u00edstica. Graduado en La Habana hace ya muchos a\u00f1os, luego de una accidentada y polvorienta b\u00fasqueda de informaci\u00f3n sobre un tema in\u00e9dito. La Tesis, por cierto, desapareci\u00f3 de la biblioteca y no se conservan copias de la misma.","url":"https:\/\/www.cuballama.com\/noticias\/author\/roberto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/96116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/comments?post=96116"}],"version-history":[{"count":3,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/96116\/revisions"}],"predecessor-version":[{"id":96161,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/96116\/revisions\/96161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media\/96124"}],"wp:attachment":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media?parent=96116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/categories?post=96116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/tags?post=96116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}