{"id":80138,"date":"2021-11-08T17:03:25","date_gmt":"2021-11-08T22:03:25","guid":{"rendered":"https:\/\/www.cuballama.com\/noticias\/?p=80138"},"modified":"2021-11-10T20:23:02","modified_gmt":"2021-11-11T01:23:02","slug":"relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores","status":"publish","type":"post","link":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/","title":{"rendered":"Relatores de la ONU solicitan informaci\u00f3n al gobierno cubano sobre detenciones y represi\u00f3n contra activistas opositores"},"content":{"rendered":"\n<p>La Relator\u00eda Especial Naciones Unidas (ONU) sobre la situaci\u00f3n de los Defensores de Derechos Humanos, el Grupo de Trabajo sobre la Detenci\u00f3n Arbitraria, la Relator\u00eda Especial sobre la promoci\u00f3n y protecci\u00f3n del derecho a la libertad de opini\u00f3n y de expresi\u00f3n y la Relator\u00eda Especial sobre los derechos a la libertad de reuni\u00f3n pac\u00edfica y de asociaci\u00f3n, solicitaron al informaci\u00f3n al gobierno cubano a trav\u00e9s de sus relatores sobre las \u201camenazas, vigilancia y supuestas detenciones arbitrarias\u201d contra opositores, periodistas independientes y defensores de los derechos humanos en la Isla.<\/p>\n\n\n\n<p>Los relatores de la ONU mostraron preocupaci\u00f3n por el incremento de la represi\u00f3n en Cuba durante la pandemia de COVID-19, cuando las autoridades cubanas \u201chabr\u00edan aplicado medidas destinadas a restringir varios derechos, entre los que se incluyen la libertad de opini\u00f3n y expresi\u00f3n, la libertad de reuni\u00f3n, asociaci\u00f3n y circulaci\u00f3n, adem\u00e1s de limitaciones a la movilidad con toque de queda en varias zonas del pa\u00eds\u00bb, de acuerdo con una misiva citada por Europapress.<\/p>\n\n\n\n<p>En la carta, enviaron al gobierno encabezado por Miguel D\u00edaz-Canel las alegaciones que han recibido sobre violaciones de derechos en la Isla y aludieron tambi\u00e9n a un comunicado de la Comisi\u00f3n Interamericana de Derechos Humanos (CIDH) que se\u00f1ala \u00abuna pr\u00e1ctica de persecuci\u00f3n y hostigamiento en contra de periodistas y medios independientes, defensores y defensoras de Derechos Humanos y artistas que denuncian la falta de libertades y derechos pol\u00edticos o participan de asuntos pol\u00edticos\u00bb.<\/p>\n\n\n\n<p>\u00abSin pretender prejuzgar la veracidad de la informaci\u00f3n recibida, quisi\u00e9ramos expresar nuestra m\u00e1s profunda preocupaci\u00f3n respecto a los alegatos sobre la criminalizaci\u00f3n y presuntas detenciones arbitrarias de personas defensoras de Derechos Humanos y periodistas por el trabajo que realizan en la denuncia de violaciones a los Derechos Humanos\u00bb, agrega la misiva, citada por la agencia <a href=\"https:\/\/www.europapress.es\/internacional\/noticia-relatores-onu-piden-informacion-gobierno-cuba-activistas-detenidos-20211108145746.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Europapress<\/a>.<\/p>\n\n\n\n<p>Asimismo, los relatores de la ONU pidieron informaci\u00f3n sobre \u00abpresuntas detenciones arbitrarias\u201d contra defensores de derechos humanos en Cuba.\u00a0<\/p>\n\n\n\n<p>Igualmente, los relatores de la ONU expresaron inquietud sobre la \u201cvigilancia, amenazas, hostigamientos\u201d, adem\u00e1s de \u201callanamientos, prohibiciones de viaje y cortes del servicio de telefon\u00eda e Internet\u201d a personas que participaron en las protestas antigubernamentales del 11 y 12 de julio pasados, o que han denunciado lo ocurrido durante las manifestaciones en redes sociales.\u00a0<\/p>\n\n\n\n<p>Los representantes de Naciones Unidas temen que las autoridades cubanas est\u00e9n utilizando las detenciones y otro tipo de ataques como m\u00e9todo de intimidaci\u00f3n contra los defensores de los derechos humanos, seg\u00fan reconocieron.&nbsp;<\/p>\n\n\n\n<p>\u00abLamentamos que, de ser verificados estos hechos, formar\u00edan parte de un aparente patr\u00f3n de represi\u00f3n hacia las actividades de los defensores de Derechos Humanos, y en particular hacia el libre ejercicio de la libertad de expresi\u00f3n\u00bb, concluyen los relatores de la ONU su misiva, quienes pidieron respuesta del gobierno de la isla en un plazo de 60 d\u00edas.<\/p>\n\n\n\n<p>El pasado 11 de julio Cuba vivi\u00f3 la mayor muestra de descontento contra el gobierno desde mediados de la d\u00e9cada de los a\u00f1os 90.&nbsp;<\/p>\n\n\n\n<p>Con el pueblo lanzado a las calles de varias ciudades de la Isla, el presidente D\u00edaz-Canel apareci\u00f3 en la televisi\u00f3n estatal y se refiri\u00f3 a los manifestantes como personas confundidas, al tiempo que dio la \u201corden de combate\u201d a sus seguidores y a las fuerzas del orden para \u201cdefender la revoluci\u00f3n\u201d.<\/p>\n\n\n\n<p>Desde entonces, las autoridades desataron una ola de represi\u00f3n, detenciones, actos de repudio y campa\u00f1as de desprestigio contra los opositores que marcan el d\u00eda a d\u00eda del pa\u00eds, mientras los voceros del gobierno niegan tales violaciones, o las justifican, alegando el derecho a la defensa del \u201ccar\u00e1cter irrevocable\u201d del socialismo, refrendado en la constituci\u00f3n.\u00a0 \u00a0<\/p>\n\n\n\n<p><strong>Noticia relacionada: <a href=\"https:\/\/www.cuballama.com\/noticias\/onu-advierte-al-gobierno-cubano-libertad-de-expresion\/\">La ONU advierte al gobierno cubano que no limite la libertad de expresi\u00f3n<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aumenta la preocupaci\u00f3n por las \u201camenazas, vigilancia y supuestas detenciones arbitrarias\u201d en Cuba contra opositores y defensores de los derechos.<\/p>\n","protected":false},"author":24,"featured_media":80160,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[955,11024,953],"tags":[941,11862,11829],"class_list":{"0":"post-80138","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-de-cuba","8":"category-noticias-de-miami","9":"category-usa","10":"tag-destacado","11":"tag-detenciones-en-cuba","12":"tag-presos-en-cuba"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Relatores de la ONU solicitan informaci\u00f3n a Cuba sobre detenciones<\/title>\n<meta name=\"description\" content=\"Aumenta la preocupaci\u00f3n entre los relatores de la ONU por \u201camenazas, vigilancia y supuestas detenciones arbitrarias\u201d en Cuba contra activistas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Relatores de la ONU solicitan informaci\u00f3n a Cuba sobre detenciones\" \/>\n<meta property=\"og:description\" content=\"Aumenta la preocupaci\u00f3n entre los relatores de la ONU por \u201camenazas, vigilancia y supuestas detenciones arbitrarias\u201d en Cuba contra activistas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuballama Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CubaLlama\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-08T22:03:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-11T01:23:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuballama.com\/noticias\/wp-content\/uploads\/2021\/11\/IMG_20211108_203151-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Manu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuballama\" \/>\n<meta name=\"twitter:site\" content=\"@cuballama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/\"},\"author\":{\"name\":\"Manu\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/5889f7d070564f8386e7944d14d436cd\"},\"headline\":\"Relatores de la ONU solicitan informaci\u00f3n al gobierno cubano sobre detenciones y represi\u00f3n contra activistas opositores\",\"datePublished\":\"2021-11-08T22:03:25+00:00\",\"dateModified\":\"2021-11-11T01:23:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/\"},\"wordCount\":675,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/08170725\\\/IMG_20211108_203151-scaled.jpg\",\"keywords\":[\"destacado\",\"detenciones en Cuba\",\"presos en Cuba\"],\"articleSection\":[\"Noticias de Cuba\",\"Noticias de Miami\",\"USA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/\",\"name\":\"Relatores de la ONU solicitan informaci\u00f3n a Cuba sobre detenciones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/08170725\\\/IMG_20211108_203151-scaled.jpg\",\"datePublished\":\"2021-11-08T22:03:25+00:00\",\"dateModified\":\"2021-11-11T01:23:02+00:00\",\"description\":\"Aumenta la preocupaci\u00f3n entre los relatores de la ONU por \u201camenazas, vigilancia y supuestas detenciones arbitrarias\u201d en Cuba contra activistas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/08170725\\\/IMG_20211108_203151-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/08170725\\\/IMG_20211108_203151-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Foto: Cuba Noticias 360.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Relatores de la ONU solicitan informaci\u00f3n al gobierno cubano sobre detenciones y represi\u00f3n contra activistas opositores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"name\":\"Cuballama Noticias\",\"description\":\"Medio digital sobre Cuba y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\",\"name\":\"Cuballama\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"width\":600,\"height\":133,\"caption\":\"Cuballama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CubaLlama\",\"https:\\\/\\\/x.com\\\/cuballama\",\"https:\\\/\\\/www.instagram.com\\\/stories\\\/cuballama_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKkFE-d_axENGZcrc4as0IA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/5889f7d070564f8386e7944d14d436cd\",\"name\":\"Manu\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/author\\\/manu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Relatores de la ONU solicitan informaci\u00f3n a Cuba sobre detenciones","description":"Aumenta la preocupaci\u00f3n entre los relatores de la ONU por \u201camenazas, vigilancia y supuestas detenciones arbitrarias\u201d en Cuba contra activistas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/","og_locale":"es_ES","og_type":"article","og_title":"Relatores de la ONU solicitan informaci\u00f3n a Cuba sobre detenciones","og_description":"Aumenta la preocupaci\u00f3n entre los relatores de la ONU por \u201camenazas, vigilancia y supuestas detenciones arbitrarias\u201d en Cuba contra activistas","og_url":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/","og_site_name":"Cuballama Noticias","article_publisher":"https:\/\/www.facebook.com\/CubaLlama","article_published_time":"2021-11-08T22:03:25+00:00","article_modified_time":"2021-11-11T01:23:02+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.cuballama.com\/noticias\/wp-content\/uploads\/2021\/11\/IMG_20211108_203151-scaled.jpg","type":"image\/jpeg"}],"author":"Manu","twitter_card":"summary_large_image","twitter_creator":"@cuballama","twitter_site":"@cuballama","twitter_misc":{"Escrito por":"Manu","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/#article","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/"},"author":{"name":"Manu","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/5889f7d070564f8386e7944d14d436cd"},"headline":"Relatores de la ONU solicitan informaci\u00f3n al gobierno cubano sobre detenciones y represi\u00f3n contra activistas opositores","datePublished":"2021-11-08T22:03:25+00:00","dateModified":"2021-11-11T01:23:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/"},"wordCount":675,"publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/11\/08170725\/IMG_20211108_203151-scaled.jpg","keywords":["destacado","detenciones en Cuba","presos en Cuba"],"articleSection":["Noticias de Cuba","Noticias de Miami","USA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/","url":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/","name":"Relatores de la ONU solicitan informaci\u00f3n a Cuba sobre detenciones","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/#primaryimage"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/11\/08170725\/IMG_20211108_203151-scaled.jpg","datePublished":"2021-11-08T22:03:25+00:00","dateModified":"2021-11-11T01:23:02+00:00","description":"Aumenta la preocupaci\u00f3n entre los relatores de la ONU por \u201camenazas, vigilancia y supuestas detenciones arbitrarias\u201d en Cuba contra activistas","breadcrumb":{"@id":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/#primaryimage","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/11\/08170725\/IMG_20211108_203151-scaled.jpg","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/11\/08170725\/IMG_20211108_203151-scaled.jpg","width":2560,"height":1707,"caption":"Foto: Cuba Noticias 360."},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuballama.com\/noticias\/relatores-de-la-onu-solicitan-informacion-al-gobierno-cubano-sobre-detenciones-y-represion-contra-activistas-opositores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cuballama.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Relatores de la ONU solicitan informaci\u00f3n al gobierno cubano sobre detenciones y represi\u00f3n contra activistas opositores"}]},{"@type":"WebSite","@id":"https:\/\/www.cuballama.com\/noticias\/#website","url":"https:\/\/www.cuballama.com\/noticias\/","name":"Cuballama Noticias","description":"Medio digital sobre Cuba y el mundo","publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuballama.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cuballama.com\/noticias\/#organization","name":"Cuballama","url":"https:\/\/www.cuballama.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","width":600,"height":133,"caption":"Cuballama"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CubaLlama","https:\/\/x.com\/cuballama","https:\/\/www.instagram.com\/stories\/cuballama_oficial\/","https:\/\/www.youtube.com\/channel\/UCKkFE-d_axENGZcrc4as0IA"]},{"@type":"Person","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/5889f7d070564f8386e7944d14d436cd","name":"Manu","url":"https:\/\/www.cuballama.com\/noticias\/author\/manu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/80138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/comments?post=80138"}],"version-history":[{"count":6,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/80138\/revisions"}],"predecessor-version":[{"id":80561,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/80138\/revisions\/80561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media\/80160"}],"wp:attachment":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media?parent=80138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/categories?post=80138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/tags?post=80138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}