{"id":246405,"date":"2026-05-29T08:56:19","date_gmt":"2026-05-29T12:56:19","guid":{"rendered":"https:\/\/www.cuballama.com\/noticias\/?p=246405"},"modified":"2026-05-29T08:56:22","modified_gmt":"2026-05-29T12:56:22","slug":"investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila","status":"publish","type":"post","link":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/","title":{"rendered":"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Una denuncia difundida en redes sociales ha generado conmoci\u00f3n en Mor\u00f3n, Ciego de \u00c1vila, tras se\u00f1alar que una madre cubana estar\u00eda siendo investigada por la muerte de su beb\u00e9 reci\u00e9n nacido, cuyo cuerpo habr\u00eda sido encontrado presuntamente dentro de una lavadora durante un registro policial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mujer fue identificada en publicaciones p\u00fablicas como Arianna Fern\u00e1ndez Bernal, madre de dos ni\u00f1as peque\u00f1as. Hasta el momento, no se ha informado de manera oficial sobre el caso por parte de la Polic\u00eda, la Fiscal\u00eda o medios estatales cubanos, por lo que los detalles conocidos proceden de denuncias ciudadanas y reportes independientes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La mujer dio a luz en casa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La creadora de contenido Glenda Ranca\u00f1o asegur\u00f3 en Facebook que la mujer habr\u00eda acudido a un centro m\u00e9dico para atenderse por un sangramiento. Seg\u00fan su versi\u00f3n, all\u00ed se habr\u00eda descubierto que \u201cten\u00eda la placenta adentro\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre el beb\u00e9 Ranca\u00f1o afirm\u00f3 adem\u00e1s: \u201cLo ahog\u00f3 con trapos y lo meti\u00f3 dentro de una lavadora rusa\u201d. En su publicaci\u00f3n tambi\u00e9n alert\u00f3 que la mujer tendr\u00eda presuntamente un cargo de fiscal en La Habana, por lo que el caso se estar\u00eda manejando \u201cbajo perfil\u201d.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fglenda.rancano.73%2Fposts%2Fpfbid026kyVBeT96kLdPe4vZ9nuA5EsPqHb8yqHNafYk3nBXNgHgbaAWUgUuLbL4HNP3usQl&#038;show_text=true&#038;width=500\" width=\"500\" height=\"725\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\">Esa afirmaci\u00f3n, por su gravedad, necesita confirmaci\u00f3n independiente. Hasta ahora no se han divulgado documentos oficiales, declaraciones institucionales ni informaci\u00f3n judicial que permitan verificar si la acusada ocupa realmente un cargo dentro del sistema fiscal cubano.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El caso habr\u00eda salido a la luz tras una atenci\u00f3n m\u00e9dica<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con las versiones divulgadas, la mujer habr\u00eda sido detenida por la polic\u00eda y habr\u00eda confesado durante la madrugada del jueves. Posteriormente, las autoridades habr\u00edan realizado un registro en una vivienda, donde presuntamente fue encontrado el cad\u00e1ver del reci\u00e9n nacido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El periodista independiente Niover Licea, a trav\u00e9s de su p\u00e1gina Nio Reportando Un Crimen, difundi\u00f3 un reporte atribuido a colaboradores y residentes de la zona:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSeg\u00fan la informaci\u00f3n recibida por diferentes colaboradores y residentes de la zona, una joven mujer habr\u00eda llegado al Hospital General Docente Roberto Rodr\u00edguez con abundante sangrado, alegando inicialmente haber sufrido un aborto.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid0n3D2mxWu5zCpnDj7sRSEP28bzER2YSyEXWC2TaQTk7Sz21Nypngojd1f6vaUPmeFl%26id%3D61559784217848&#038;show_text=true&#038;width=500\" width=\"500\" height=\"519\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, de acuerdo con estos testimonios, posteriormente las autoridades habr\u00edan localizado dentro de una vivienda el cuerpo de un reci\u00e9n nacido, presuntamente oculto en una lavadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las versiones recibidas aseguran que el beb\u00e9 habr\u00eda sido hallado envuelto en s\u00e1banas y que el caso se encuentra bajo investigaci\u00f3n de las autoridades competentes.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Hospital General Docente Roberto Rodr\u00edguez est\u00e1 ubicado en Mor\u00f3n, municipio de Ciego de \u00c1vila, y es una de las principales instituciones sanitarias de la zona.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sin confirmaci\u00f3n oficial sobre la investigaci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Por ahora, no se conocen detalles oficiales sobre la edad exacta del beb\u00e9, las circunstancias del nacimiento, la causa de muerte ni el estado procesal de la mujer se\u00f1alada. Tampoco se ha informado si existen otros familiares investigados o testigos directos del hecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lea m\u00e1s: <a href=\"https:\/\/www.cuballama.com\/noticias\/kosun-el-bebe-de-diez-meses-que-sobrevivio-al-mal-en-camaguey\/?srsltid=AfmBOooey34QD6IIDitm8_NkGIG0Q5Gr_UyVwyZY3UTQJ0MB8aslkJmk\" target=\"_blank\" rel=\"noreferrer noopener\">Kos\u00fan, el beb\u00e9 de diez meses que sobrevivi\u00f3 al mal en Camag\u00fcey<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ausencia de una versi\u00f3n institucional obliga a tratar la informaci\u00f3n con cautela. Las denuncias p\u00fablicas apuntan a un presunto infanticidio, pero solo una investigaci\u00f3n oficial y peritajes forenses podr\u00edan establecer qu\u00e9 ocurri\u00f3, cu\u00e1ndo muri\u00f3 el beb\u00e9 y qui\u00e9nes tendr\u00edan responsabilidad penal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El caso ha provocado indignaci\u00f3n entre usuarios cubanos en redes sociales, especialmente por la vulnerabilidad de la v\u00edctima y por las versiones que apuntan a un posible intento de ocultamiento del cuerpo. Sin embargo, hasta que las autoridades emitan informaci\u00f3n verificable, los datos disponibles deben entenderse como reportes preliminares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La madre acudi\u00f3 al hospital alegando haber sufrido una p\u00e9rdida<\/p>\n","protected":false},"author":27,"featured_media":246406,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[955],"tags":[26155,16558,11258,5813],"class_list":["post-246405","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-de-cuba","tag-bebe-cubano","tag-bebe-muerto","tag-ciego-de-avila-2","tag-moron"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila - Cuballama Noticias<\/title>\n<meta name=\"description\" content=\"La mujer fue identificada en publicaciones p\u00fablicas como Arianna Fern\u00e1ndez Bernal, madre de dos ni\u00f1as peque\u00f1as\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila - Cuballama Noticias\" \/>\n<meta property=\"og:description\" content=\"La mujer fue identificada en publicaciones p\u00fablicas como Arianna Fern\u00e1ndez Bernal, madre de dos ni\u00f1as peque\u00f1as\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuballama Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CubaLlama\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-29T12:56:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T12:56:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/29084831\/Cubana-asesina-a-su-bebe-recien-nacida-en-Ciego-de-Avila.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rafa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuballama\" \/>\n<meta name=\"twitter:site\" content=\"@cuballama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/\"},\"author\":{\"name\":\"Rafa\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/0f97914526a658755f00e59ec2a832f2\"},\"headline\":\"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila\",\"datePublished\":\"2026-05-29T12:56:19+00:00\",\"dateModified\":\"2026-05-29T12:56:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/\"},\"wordCount\":643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/29084831\\\/Cubana-asesina-a-su-bebe-recien-nacida-en-Ciego-de-Avila.png\",\"keywords\":[\"beb\u00e9 cubano\",\"beb\u00e9 muerto\",\"Ciego de \u00c1vila\",\"Mor\u00f3n\"],\"articleSection\":[\"Noticias de Cuba\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/\",\"name\":\"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila - Cuballama Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/29084831\\\/Cubana-asesina-a-su-bebe-recien-nacida-en-Ciego-de-Avila.png\",\"datePublished\":\"2026-05-29T12:56:19+00:00\",\"dateModified\":\"2026-05-29T12:56:22+00:00\",\"description\":\"La mujer fue identificada en publicaciones p\u00fablicas como Arianna Fern\u00e1ndez Bernal, madre de dos ni\u00f1as peque\u00f1as\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/29084831\\\/Cubana-asesina-a-su-bebe-recien-nacida-en-Ciego-de-Avila.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/29084831\\\/Cubana-asesina-a-su-bebe-recien-nacida-en-Ciego-de-Avila.png\",\"width\":1400,\"height\":920,\"caption\":\"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila (Captura de pantalla\\\/ Canal Caribe)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"name\":\"Cuballama Noticias\",\"description\":\"Medio digital sobre Cuba y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\",\"name\":\"Cuballama\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"width\":600,\"height\":133,\"caption\":\"Cuballama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CubaLlama\",\"https:\\\/\\\/x.com\\\/cuballama\",\"https:\\\/\\\/www.instagram.com\\\/stories\\\/cuballama_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKkFE-d_axENGZcrc4as0IA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/0f97914526a658755f00e59ec2a832f2\",\"name\":\"Rafa\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/author\\\/rafa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila - Cuballama Noticias","description":"La mujer fue identificada en publicaciones p\u00fablicas como Arianna Fern\u00e1ndez Bernal, madre de dos ni\u00f1as peque\u00f1as","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/","og_locale":"es_ES","og_type":"article","og_title":"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila - Cuballama Noticias","og_description":"La mujer fue identificada en publicaciones p\u00fablicas como Arianna Fern\u00e1ndez Bernal, madre de dos ni\u00f1as peque\u00f1as","og_url":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/","og_site_name":"Cuballama Noticias","article_publisher":"https:\/\/www.facebook.com\/CubaLlama","article_published_time":"2026-05-29T12:56:19+00:00","article_modified_time":"2026-05-29T12:56:22+00:00","og_image":[{"width":1400,"height":920,"url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/29084831\/Cubana-asesina-a-su-bebe-recien-nacida-en-Ciego-de-Avila.png","type":"image\/png"}],"author":"Rafa","twitter_card":"summary_large_image","twitter_creator":"@cuballama","twitter_site":"@cuballama","twitter_misc":{"Escrito por":"Rafa","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/#article","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/"},"author":{"name":"Rafa","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/0f97914526a658755f00e59ec2a832f2"},"headline":"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila","datePublished":"2026-05-29T12:56:19+00:00","dateModified":"2026-05-29T12:56:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/"},"wordCount":643,"commentCount":0,"publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/29084831\/Cubana-asesina-a-su-bebe-recien-nacida-en-Ciego-de-Avila.png","keywords":["beb\u00e9 cubano","beb\u00e9 muerto","Ciego de \u00c1vila","Mor\u00f3n"],"articleSection":["Noticias de Cuba"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/","url":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/","name":"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila - Cuballama Noticias","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/#primaryimage"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/29084831\/Cubana-asesina-a-su-bebe-recien-nacida-en-Ciego-de-Avila.png","datePublished":"2026-05-29T12:56:19+00:00","dateModified":"2026-05-29T12:56:22+00:00","description":"La mujer fue identificada en publicaciones p\u00fablicas como Arianna Fern\u00e1ndez Bernal, madre de dos ni\u00f1as peque\u00f1as","breadcrumb":{"@id":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/#primaryimage","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/29084831\/Cubana-asesina-a-su-bebe-recien-nacida-en-Ciego-de-Avila.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/29084831\/Cubana-asesina-a-su-bebe-recien-nacida-en-Ciego-de-Avila.png","width":1400,"height":920,"caption":"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila (Captura de pantalla\/ Canal Caribe)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuballama.com\/noticias\/investigan-el-hallazgo-de-un-bebe-dentro-de-una-lavadora-en-ciego-de-avila\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cuballama.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Investigan el hallazgo de un beb\u00e9 dentro de una lavadora en Ciego de \u00c1vila"}]},{"@type":"WebSite","@id":"https:\/\/www.cuballama.com\/noticias\/#website","url":"https:\/\/www.cuballama.com\/noticias\/","name":"Cuballama Noticias","description":"Medio digital sobre Cuba y el mundo","publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuballama.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cuballama.com\/noticias\/#organization","name":"Cuballama","url":"https:\/\/www.cuballama.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","width":600,"height":133,"caption":"Cuballama"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CubaLlama","https:\/\/x.com\/cuballama","https:\/\/www.instagram.com\/stories\/cuballama_oficial\/","https:\/\/www.youtube.com\/channel\/UCKkFE-d_axENGZcrc4as0IA"]},{"@type":"Person","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/0f97914526a658755f00e59ec2a832f2","name":"Rafa","url":"https:\/\/www.cuballama.com\/noticias\/author\/rafa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/246405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/comments?post=246405"}],"version-history":[{"count":1,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/246405\/revisions"}],"predecessor-version":[{"id":246415,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/246405\/revisions\/246415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media\/246406"}],"wp:attachment":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media?parent=246405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/categories?post=246405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/tags?post=246405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}