{"id":245458,"date":"2026-05-23T09:00:13","date_gmt":"2026-05-23T13:00:13","guid":{"rendered":"https:\/\/www.cuballama.com\/noticias\/?p=245458"},"modified":"2026-05-23T09:00:17","modified_gmt":"2026-05-23T13:00:17","slug":"joven-cubano-muere-en-accidente-de-trabajo-en-texas","status":"publish","type":"post","link":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/","title":{"rendered":"Joven cubano muere en accidente de trabajo en Texas"},"content":{"rendered":"\n<p>Un joven cubano identificado como Pedro Pablo Poll\u00e1n Ortiz perdi\u00f3 la vida en un accidente laboral ocurrido en la ciudad estadounidense de Odessa, Texas, el pasado martes 19 de mayo, seg\u00fan reportes en redes sociales.<\/p>\n\n\n\n<p>El activista Niover Licea confirm\u00f3 a trav\u00e9s de su p\u00e1gina Nio reportando un crimen, que el muchacho de 30 a\u00f1os y residente en Houston trabajaba como soldador cuando la explosi\u00f3n en un tr\u00e1iler \u201cde los que tira arena en los pozos de petr\u00f3leo\u201d le provoc\u00f3 heridas fatales.<\/p>\n\n\n\n<p>\u201cUn tanque de carga de arena explot\u00f3 mientras le sacaban unos baches y as\u00ed perdi\u00f3 la vida\u201d, detall\u00f3 en Facebook Sucel Hern\u00e1ndez, radicada en Odessa, al aclarar que la explosi\u00f3n no fue provocada por un rayo, como indicaron versiones preliminares.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=476&#038;href=https%3A%2F%2Fwww.facebook.com%2Freel%2F1662475861562487%2F&#038;show_text=true&#038;width=267&#038;t=0\" width=\"267\" height=\"591\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\" allowFullScreen=\"true\"><\/iframe>\n\n\n\n<p>La misma internauta precis\u00f3 que Poll\u00e1n Ortiz estaba trabajando con unos primos que hab\u00edan abierto recientemente su negocio.<\/p>\n\n\n\n<p>\u201cNo dio tiempo a hacer absolutamente nada. Los param\u00e9dicos no pudieron reanimarlo\u201d, precis\u00f3 Licea sobre la tr\u00e1gica muerte del joven natural de Veguitas, en la provincia de Granma, que llevaba m\u00e1s de tres a\u00f1os viviendo en Estados Unidos.<\/p>\n\n\n\n<p>Tras el triste suceso, Evelin, la hermana de Poll\u00e1n Ortiz, y otros de sus seres queridos han pedido ayuda a la comunidad cubana para lograr reunir los fondos necesarios para repatriar su cuerpo y darle una despedida digna.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"598\" height=\"1024\" src=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/23085258\/WhatsApp-Image-2026-05-23-at-08.51.41-598x1024.jpeg\" alt=\"\" class=\"wp-image-245465\" srcset=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/23085258\/WhatsApp-Image-2026-05-23-at-08.51.41-598x1024.jpeg 598w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/23085258\/WhatsApp-Image-2026-05-23-at-08.51.41-175x300.jpeg 175w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/23085258\/WhatsApp-Image-2026-05-23-at-08.51.41-768x1315.jpeg 768w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/23085258\/WhatsApp-Image-2026-05-23-at-08.51.41-897x1536.jpeg 897w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/23085258\/WhatsApp-Image-2026-05-23-at-08.51.41-245x420.jpeg 245w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/23085258\/WhatsApp-Image-2026-05-23-at-08.51.41-150x257.jpeg 150w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/23085258\/WhatsApp-Image-2026-05-23-at-08.51.41-300x514.jpeg 300w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/23085258\/WhatsApp-Image-2026-05-23-at-08.51.41-696x1192.jpeg 696w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/23085258\/WhatsApp-Image-2026-05-23-at-08.51.41-1068x1829.jpeg 1068w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/23085258\/WhatsApp-Image-2026-05-23-at-08.51.41.jpeg 1196w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><\/figure>\n\n\n\n<p>\u201cMi amigo de toda la vida, desde peque\u00f1os hasta el d\u00eda que te fuiste, cuando te desped\u00ed. Humilde hasta los huesos, trabajador hasta el cansancio, de familia que daba hasta lo que no ten\u00eda por todos los vecinos\u201d, expres\u00f3 una amiga, identificada como Snatali BC, que pidi\u00f3 ayuda para lograr devolver su cuerpo a la isla.\u00a0<\/p>\n\n\n\n<p>\u201cMi vecino, que lo vi nacer y crecer. Buen muchacho. Nunca lo olvidaremos. Es una p\u00e9rdida muy fuerte. Pedro, nunca te olvidaremos\u201d; y \u201cEsto no ha sido f\u00e1cil. Era un muchacho noble, trabajador, respetuoso. Sus padres est\u00e1n destruidos\u201d, comentaron otros de sus allegados.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Varios de sus seres queridos han pedido ayuda a la comunidad cubana para poder repatriar su cuerpo.<\/p>\n","protected":false},"author":30,"featured_media":245460,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,953],"tags":[29073,27425,22579,19611,941,13408,6078],"class_list":{"0":"post-245458","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"category-usa","9":"tag-accidente-de-trabajo","10":"tag-accidente-laboral","11":"tag-cubano-fallecido","12":"tag-cubanos-en-texas","13":"tag-destacado","14":"tag-joven-cubano","15":"tag-odessa"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joven cubano muere en accidente de trabajo en Texas - Cuballama Noticias<\/title>\n<meta name=\"description\" content=\"Un joven cubano identificado como Pedro Pablo Poll\u00e1n Ortiz perdi\u00f3 la vida en un accidente de trabajo en la ciudad estadounidense de Odessa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joven cubano muere en accidente de trabajo en Texas - Cuballama Noticias\" \/>\n<meta property=\"og:description\" content=\"Un joven cubano identificado como Pedro Pablo Poll\u00e1n Ortiz perdi\u00f3 la vida en un accidente de trabajo en la ciudad estadounidense de Odessa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuballama Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CubaLlama\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-23T13:00:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-23T13:00:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/22232105\/698607090_122220207854321566_2800680658173536810_n1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kathy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuballama\" \/>\n<meta name=\"twitter:site\" content=\"@cuballama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kathy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/\"},\"author\":{\"name\":\"Kathy\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/86cd3e3f4974437f031211213bf892d5\"},\"headline\":\"Joven cubano muere en accidente de trabajo en Texas\",\"datePublished\":\"2026-05-23T13:00:13+00:00\",\"dateModified\":\"2026-05-23T13:00:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/\"},\"wordCount\":345,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/22232105\\\/698607090_122220207854321566_2800680658173536810_n1.jpg\",\"keywords\":[\"accidente de trabajo\",\"accidente laboral\",\"cubano fallecido\",\"cubanos en Texas\",\"destacado\",\"joven cubano\",\"Odessa\"],\"articleSection\":[\"Noticias\",\"USA\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/\",\"name\":\"Joven cubano muere en accidente de trabajo en Texas - Cuballama Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/22232105\\\/698607090_122220207854321566_2800680658173536810_n1.jpg\",\"datePublished\":\"2026-05-23T13:00:13+00:00\",\"dateModified\":\"2026-05-23T13:00:17+00:00\",\"description\":\"Un joven cubano identificado como Pedro Pablo Poll\u00e1n Ortiz perdi\u00f3 la vida en un accidente de trabajo en la ciudad estadounidense de Odessa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/22232105\\\/698607090_122220207854321566_2800680658173536810_n1.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/22232105\\\/698607090_122220207854321566_2800680658173536810_n1.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Pedro Pablo Poll\u00e1n Ortiz. Foto: Facebook\\\/Pedro Pablo Poll\u00e1n Ortiz.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joven cubano muere en accidente de trabajo en Texas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"name\":\"Cuballama Noticias\",\"description\":\"Medio digital sobre Cuba y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\",\"name\":\"Cuballama\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"width\":600,\"height\":133,\"caption\":\"Cuballama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CubaLlama\",\"https:\\\/\\\/x.com\\\/cuballama\",\"https:\\\/\\\/www.instagram.com\\\/stories\\\/cuballama_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKkFE-d_axENGZcrc4as0IA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/86cd3e3f4974437f031211213bf892d5\",\"name\":\"Kathy\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/author\\\/kathy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joven cubano muere en accidente de trabajo en Texas - Cuballama Noticias","description":"Un joven cubano identificado como Pedro Pablo Poll\u00e1n Ortiz perdi\u00f3 la vida en un accidente de trabajo en la ciudad estadounidense de Odessa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/","og_locale":"es_ES","og_type":"article","og_title":"Joven cubano muere en accidente de trabajo en Texas - Cuballama Noticias","og_description":"Un joven cubano identificado como Pedro Pablo Poll\u00e1n Ortiz perdi\u00f3 la vida en un accidente de trabajo en la ciudad estadounidense de Odessa.","og_url":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/","og_site_name":"Cuballama Noticias","article_publisher":"https:\/\/www.facebook.com\/CubaLlama","article_published_time":"2026-05-23T13:00:13+00:00","article_modified_time":"2026-05-23T13:00:17+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/22232105\/698607090_122220207854321566_2800680658173536810_n1.jpg","type":"image\/jpeg"}],"author":"Kathy","twitter_card":"summary_large_image","twitter_creator":"@cuballama","twitter_site":"@cuballama","twitter_misc":{"Escrito por":"Kathy","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/#article","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/"},"author":{"name":"Kathy","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/86cd3e3f4974437f031211213bf892d5"},"headline":"Joven cubano muere en accidente de trabajo en Texas","datePublished":"2026-05-23T13:00:13+00:00","dateModified":"2026-05-23T13:00:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/"},"wordCount":345,"commentCount":0,"publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/22232105\/698607090_122220207854321566_2800680658173536810_n1.jpg","keywords":["accidente de trabajo","accidente laboral","cubano fallecido","cubanos en Texas","destacado","joven cubano","Odessa"],"articleSection":["Noticias","USA"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/","url":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/","name":"Joven cubano muere en accidente de trabajo en Texas - Cuballama Noticias","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/#primaryimage"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/22232105\/698607090_122220207854321566_2800680658173536810_n1.jpg","datePublished":"2026-05-23T13:00:13+00:00","dateModified":"2026-05-23T13:00:17+00:00","description":"Un joven cubano identificado como Pedro Pablo Poll\u00e1n Ortiz perdi\u00f3 la vida en un accidente de trabajo en la ciudad estadounidense de Odessa.","breadcrumb":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/#primaryimage","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/22232105\/698607090_122220207854321566_2800680658173536810_n1.jpg","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/22232105\/698607090_122220207854321566_2800680658173536810_n1.jpg","width":1200,"height":630,"caption":"Pedro Pablo Poll\u00e1n Ortiz. Foto: Facebook\/Pedro Pablo Poll\u00e1n Ortiz."},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuballama.com\/noticias\/joven-cubano-muere-en-accidente-de-trabajo-en-texas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cuballama.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Joven cubano muere en accidente de trabajo en Texas"}]},{"@type":"WebSite","@id":"https:\/\/www.cuballama.com\/noticias\/#website","url":"https:\/\/www.cuballama.com\/noticias\/","name":"Cuballama Noticias","description":"Medio digital sobre Cuba y el mundo","publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuballama.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cuballama.com\/noticias\/#organization","name":"Cuballama","url":"https:\/\/www.cuballama.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","width":600,"height":133,"caption":"Cuballama"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CubaLlama","https:\/\/x.com\/cuballama","https:\/\/www.instagram.com\/stories\/cuballama_oficial\/","https:\/\/www.youtube.com\/channel\/UCKkFE-d_axENGZcrc4as0IA"]},{"@type":"Person","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/86cd3e3f4974437f031211213bf892d5","name":"Kathy","url":"https:\/\/www.cuballama.com\/noticias\/author\/kathy\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/245458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/comments?post=245458"}],"version-history":[{"count":3,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/245458\/revisions"}],"predecessor-version":[{"id":245467,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/245458\/revisions\/245467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media\/245460"}],"wp:attachment":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media?parent=245458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/categories?post=245458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/tags?post=245458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}