{"id":245231,"date":"2026-05-21T08:14:38","date_gmt":"2026-05-21T12:14:38","guid":{"rendered":"https:\/\/www.cuballama.com\/noticias\/?p=245231"},"modified":"2026-05-21T23:46:01","modified_gmt":"2026-05-22T03:46:01","slug":"se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos","status":"publish","type":"post","link":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/","title":{"rendered":"\u00bfSe acab\u00f3 la pausa de USCIS? Llegan entrevistas de residencia a cubanos"},"content":{"rendered":"\n<p>La abogada de inmigraci\u00f3n Claudia Ca\u00f1izares anunci\u00f3 feliz este mi\u00e9rcoles que tras una larga pausa administrativa ha recibido al menos una cita para entrevista ante el Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos (USCIS por sus siglas en ingl\u00e9s) en el caso de un cubano que opta por la residencia permanente.<\/p>\n\n\n\n<p>\u201cEsta semana por primera vez en much\u00edsimo tiempo me lleg\u00f3 una entrevista de residencia para un cubano, lo que quiere decir que Inmigraci\u00f3n s\u00ed est\u00e1 sacando varios casos de la gaveta y finalmente los est\u00e1 procesando\u201d, explic\u00f3 la cubanoamericana.&nbsp;<\/p>\n\n\n\n<p>\u201cLlev\u00e1bamos muchos meses esperando por esto. Sab\u00edamos que hab\u00eda un rumor de que los casos estaban siendo descongelados. Esto no quiere decir que los vayan a aprobar, pero ver que vayan adelantando la entrevista es un buen paso\u201d, argument\u00f3 la experta radicada en Miami, Florida.<\/p>\n\n\n\n<p>Ca\u00f1izares aprovech\u00f3 para recordar los documentos b\u00e1sicos que deben llevarse a una entrevista para obtener la green card o la ciudadan\u00eda estadounidense ante USCIS.&nbsp;<\/p>\n\n\n\n<p>En el caso de residencia, no pueden faltar el pasaporte original, el certificado de nacimiento, el certificado de matrimonio, la notificaci\u00f3n de entrevista, el permiso de trabajo, la licencia de conducir y traducciones de todos los documentos.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=476&#038;href=https%3A%2F%2Fwww.facebook.com%2Freel%2F989348617396654%2F&#038;show_text=true&#038;width=267&#038;t=0\" width=\"267\" height=\"591\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\" allowFullScreen=\"true\"><\/iframe>\n\n\n\n<p>Si debe asistir a una entrevista para convertirse en ciudadano, debe llevar todos los pasaportes que ha tenido desde que ingres\u00f3 a Estados Unidos, sus impuestos y todos los documentos mencionados en el caso de residencia, con la excepci\u00f3n del permiso de trabajo.<\/p>\n\n\n\n<p>Hay que recordar que el 2 de diciembre de 2025 el gobierno de Estados Unidos anunci\u00f3 <a href=\"https:\/\/www.cuballama.com\/noticias\/ee-uu-detiene-todas-las-solicitudes-de-inmigracion-de-19-paises-incluida-cuba\/\" target=\"_blank\" rel=\"noreferrer noopener\">una pausa inmediata<\/a> en todas las aplicaciones migratorias, incluidas las de residencia permanente y de ciudadan\u00eda estadounidense, presentadas por inmigrantes de los 19 pa\u00edses con prohibiciones o restricciones de viaje desde junio del mismo a\u00f1o.<\/p>\n\n\n\n<p>Seg\u00fan un memor\u00e1ndum de USCIS, la suspensi\u00f3n, que afecta a naciones como Cuba y Venezuela, se hac\u00eda \u201cen espera de una revisi\u00f3n exhaustiva\u201d e \u201cindependientemente de la fecha de entrada\u201d de las personas extranjeras.<\/p>\n\n\n\n<p>Entonces la agencia confirm\u00f3 que, entrevistas para green cards, ceremonias de naturalizaci\u00f3n, solicitudes de ajuste de estatus y otros beneficios migratorios han sido cancelados sin previo aviso.<\/p>\n\n\n\n<p>Desde enero pasado la suspensi\u00f3n de las resoluciones sobre prestaciones migratorias se ampli\u00f3 para incluir a ciudadanos de 39 pa\u00edses.<\/p>\n\n\n\n<p>De acuerdo con <a href=\"https:\/\/www.cuballama.com\/noticias\/estudio-muestra-que-los-cubanos-son-el-grupo-mas-afectado-por-pausa-migratoria-en-ee-uu\/\" target=\"_blank\" rel=\"noreferrer noopener\">un estudio<\/a> publicado en marzo por Cato at Liberty (Cato Institute), con casi un mill\u00f3n de solicitudes, los cubanos representan el mayor grupo de solicitantes afectados por el retraso en los tr\u00e1mites migratorios en Estados Unidos.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En diciembre de 2025 EE.UU. puso una pausa inmediata en todas las aplicaciones migratorias de cubanos y de inmigrantes de otros 18 pa\u00edses.<\/p>\n","protected":false},"author":30,"featured_media":211021,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,953],"tags":[5404,941,3475,1161,6374,29458,2022,911],"class_list":{"0":"post-245231","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"category-usa","9":"tag-administracion-trump","10":"tag-destacado","11":"tag-entrevista","12":"tag-green-card","13":"tag-ley-de-ajuste","14":"tag-pausa-migratoria","15":"tag-residencia-permanente","16":"tag-uscis"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfSe acab\u00f3 la pausa de USCIS? Llegan entrevistas de residencia a cubanos - Cuballama Noticias<\/title>\n<meta name=\"description\" content=\"El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos habr\u00eda empezado a levantar la pausa administrativa que ha afectado a cubanos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfSe acab\u00f3 la pausa de USCIS? Llegan entrevistas de residencia a cubanos - Cuballama Noticias\" \/>\n<meta property=\"og:description\" content=\"El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos habr\u00eda empezado a levantar la pausa administrativa que ha afectado a cubanos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuballama Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CubaLlama\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-21T12:14:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T03:46:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2025\/06\/21104428\/Immigration_Documents.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kathy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuballama\" \/>\n<meta name=\"twitter:site\" content=\"@cuballama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kathy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/\"},\"author\":{\"name\":\"Kathy\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/86cd3e3f4974437f031211213bf892d5\"},\"headline\":\"\u00bfSe acab\u00f3 la pausa de USCIS? Llegan entrevistas de residencia a cubanos\",\"datePublished\":\"2026-05-21T12:14:38+00:00\",\"dateModified\":\"2026-05-22T03:46:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/\"},\"wordCount\":450,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/21104428\\\/Immigration_Documents.jpg\",\"keywords\":[\"administraci\u00f3n Trump\",\"destacado\",\"entrevista\",\"green card\",\"Ley de Ajuste\",\"pausa migratoria\",\"residencia permanente\",\"USCIS\"],\"articleSection\":[\"Noticias\",\"USA\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/\",\"name\":\"\u00bfSe acab\u00f3 la pausa de USCIS? Llegan entrevistas de residencia a cubanos - Cuballama Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/21104428\\\/Immigration_Documents.jpg\",\"datePublished\":\"2026-05-21T12:14:38+00:00\",\"dateModified\":\"2026-05-22T03:46:01+00:00\",\"description\":\"El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos habr\u00eda empezado a levantar la pausa administrativa que ha afectado a cubanos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/21104428\\\/Immigration_Documents.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/21104428\\\/Immigration_Documents.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Green card. Foto: USCIS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfSe acab\u00f3 la pausa de USCIS? Llegan entrevistas de residencia a cubanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"name\":\"Cuballama Noticias\",\"description\":\"Medio digital sobre Cuba y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\",\"name\":\"Cuballama\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"width\":600,\"height\":133,\"caption\":\"Cuballama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CubaLlama\",\"https:\\\/\\\/x.com\\\/cuballama\",\"https:\\\/\\\/www.instagram.com\\\/stories\\\/cuballama_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKkFE-d_axENGZcrc4as0IA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/86cd3e3f4974437f031211213bf892d5\",\"name\":\"Kathy\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/author\\\/kathy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfSe acab\u00f3 la pausa de USCIS? Llegan entrevistas de residencia a cubanos - Cuballama Noticias","description":"El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos habr\u00eda empezado a levantar la pausa administrativa que ha afectado a cubanos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfSe acab\u00f3 la pausa de USCIS? Llegan entrevistas de residencia a cubanos - Cuballama Noticias","og_description":"El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos habr\u00eda empezado a levantar la pausa administrativa que ha afectado a cubanos.","og_url":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/","og_site_name":"Cuballama Noticias","article_publisher":"https:\/\/www.facebook.com\/CubaLlama","article_published_time":"2026-05-21T12:14:38+00:00","article_modified_time":"2026-05-22T03:46:01+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2025\/06\/21104428\/Immigration_Documents.jpg","type":"image\/jpeg"}],"author":"Kathy","twitter_card":"summary_large_image","twitter_creator":"@cuballama","twitter_site":"@cuballama","twitter_misc":{"Escrito por":"Kathy","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/#article","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/"},"author":{"name":"Kathy","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/86cd3e3f4974437f031211213bf892d5"},"headline":"\u00bfSe acab\u00f3 la pausa de USCIS? Llegan entrevistas de residencia a cubanos","datePublished":"2026-05-21T12:14:38+00:00","dateModified":"2026-05-22T03:46:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/"},"wordCount":450,"commentCount":0,"publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2025\/06\/21104428\/Immigration_Documents.jpg","keywords":["administraci\u00f3n Trump","destacado","entrevista","green card","Ley de Ajuste","pausa migratoria","residencia permanente","USCIS"],"articleSection":["Noticias","USA"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/","url":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/","name":"\u00bfSe acab\u00f3 la pausa de USCIS? Llegan entrevistas de residencia a cubanos - Cuballama Noticias","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/#primaryimage"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2025\/06\/21104428\/Immigration_Documents.jpg","datePublished":"2026-05-21T12:14:38+00:00","dateModified":"2026-05-22T03:46:01+00:00","description":"El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos habr\u00eda empezado a levantar la pausa administrativa que ha afectado a cubanos.","breadcrumb":{"@id":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/#primaryimage","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2025\/06\/21104428\/Immigration_Documents.jpg","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2025\/06\/21104428\/Immigration_Documents.jpg","width":1200,"height":630,"caption":"Green card. Foto: USCIS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuballama.com\/noticias\/se-acabo-la-pausa-de-uscis-llegan-entrevistas-de-residencia-a-cubanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cuballama.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"\u00bfSe acab\u00f3 la pausa de USCIS? Llegan entrevistas de residencia a cubanos"}]},{"@type":"WebSite","@id":"https:\/\/www.cuballama.com\/noticias\/#website","url":"https:\/\/www.cuballama.com\/noticias\/","name":"Cuballama Noticias","description":"Medio digital sobre Cuba y el mundo","publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuballama.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cuballama.com\/noticias\/#organization","name":"Cuballama","url":"https:\/\/www.cuballama.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","width":600,"height":133,"caption":"Cuballama"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CubaLlama","https:\/\/x.com\/cuballama","https:\/\/www.instagram.com\/stories\/cuballama_oficial\/","https:\/\/www.youtube.com\/channel\/UCKkFE-d_axENGZcrc4as0IA"]},{"@type":"Person","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/86cd3e3f4974437f031211213bf892d5","name":"Kathy","url":"https:\/\/www.cuballama.com\/noticias\/author\/kathy\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/245231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/comments?post=245231"}],"version-history":[{"count":5,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/245231\/revisions"}],"predecessor-version":[{"id":245370,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/245231\/revisions\/245370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media\/211021"}],"wp:attachment":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media?parent=245231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/categories?post=245231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/tags?post=245231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}