{"id":244755,"date":"2026-05-18T08:00:00","date_gmt":"2026-05-18T12:00:00","guid":{"rendered":"https:\/\/www.cuballama.com\/noticias\/?p=244755"},"modified":"2026-05-18T07:58:22","modified_gmt":"2026-05-18T11:58:22","slug":"joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu","status":"publish","type":"post","link":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/","title":{"rendered":"Joven padre cubano muere en accidente de tr\u00e1nsito en EE.UU."},"content":{"rendered":"\n<p><a href=\"https:\/\/www.cuballama.com\/noticias\/comunidad-cubana-llora-la-tragica-muerte-de-un-joven-en-ee-uu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Un joven cubano<\/a>, identificado como Julio C\u00e9sar Est\u00e9vez Garc\u00eda, perdi\u00f3 la vida en un accidente de tr\u00e1nsito en Estados Unidos el pasado viernes, seg\u00fan lamentaron familiares y amigos en redes sociales.<\/p>\n\n\n\n<p>Seg\u00fan precis\u00f3 uno de sus seres queridos en Facebook, el muchacho natural de Agramonte, Camag\u00fcey, muri\u00f3 de manera tr\u00e1gica tras sufrir \u201cun accidente en el cami\u00f3n\u201d.<\/p>\n\n\n\n<p>\u201cEstamos creando esta campa\u00f1a para pedir ayuda y apoyo para cubrir los gastos funerarios y la repatriaci\u00f3n de su cuerpo, para poder llevarlo de regreso junto a su familia y darle una despedida digna y llena de amor\u201d, puede leerse en la campa\u00f1a de recaudaci\u00f3n de fondos abierta en <a href=\"https:\/\/www.gofundme.com\/f\/julio-cesar-estevez-garcia\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">GoFundMe<\/a> para cubrir los gastos funerarios y repatriar su cuerpo a la isla.&nbsp;<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Felizabeth.mesa.410000%2Fposts%2Fpfbid02LjJoW9dTqx7Ra15rmvE5jrNMoNLkTn358DyzDLBXnwMnYA2Ammix51bkgowAhKVpl&#038;show_text=true&#038;width=500\" width=\"500\" height=\"250\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n\n\n<p>\u201cJulio fue una persona querida, trabajadora y de gran coraz\u00f3n, que dej\u00f3 una huella especial en todos los que tuvieron la oportunidad de conocerlo. Hoy necesitamos unirnos como familia y comunidad para poder cumplir su \u00faltimo deseo de descansar cerca de sus seres queridos\u201d, precisa adem\u00e1s el texto sobre un joven a quien le sobreviven una hija de 14 a\u00f1os, su madre Aimara, su padre y muchos otros familiares.<\/p>\n\n\n\n<p>Uno de sus allegados, Elizabeth Mesa, escribi\u00f3 en Facebook: \u201cJulio no era solo un joven m\u00e1s. Era un hijo ejemplar, un padre amoroso, un amigo leal y un ser humano lleno de luz. De esos muchachos nobles que siempre ten\u00edan una sonrisa, una mano amiga y un coraz\u00f3n dispuesto a ayudar. Ten\u00eda sue\u00f1os, metas y una vida entera por delante. Su alegr\u00eda contagiaba, su humildad enamoraba y su manera de querer dejaba huellas profundas\u201d.<\/p>\n\n\n\n<p>Otros conocidos lamentaron el fallecimiento de Julito, como cari\u00f1osamente llamaban a este joven \u201clleno de sue\u00f1os, ilusiones y energ\u00eda\u201d, a quien le gustaba mucho el deporte, en especial practicar el f\u00fatbol.<\/p>\n\n\n\n<p>\u201cGracias a todos por sus donaciones y por compartir en nombre de la familia\u201d, expres\u00f3 una de sus familiares, a modo de agradecimiento por los fondos reunidos en muy corto tiempo, una muestra de amor y respeto hacia un ser que parti\u00f3 de este mundo muy pronto.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El muchacho era una persona muy querida, en especial en su natal Agramonte, en Camag\u00fcey.<\/p>\n","protected":false},"author":30,"featured_media":244756,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,953],"tags":[4646,31562,22579,941],"class_list":{"0":"post-244755","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"category-usa","9":"tag-camionero-cubano","10":"tag-cubano-en-estados-unidos","11":"tag-cubano-fallecido","12":"tag-destacado"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joven padre cubano muere en accidente de tr\u00e1nsito en EE.UU. - Cuballama Noticias<\/title>\n<meta name=\"description\" content=\"Un joven padre cubano perdi\u00f3 la vida en un tr\u00e1gico accidente de tr\u00e1nsito en Estados Unidos el pasado viernes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joven padre cubano muere en accidente de tr\u00e1nsito en EE.UU. - Cuballama Noticias\" \/>\n<meta property=\"og:description\" content=\"Un joven padre cubano perdi\u00f3 la vida en un tr\u00e1gico accidente de tr\u00e1nsito en Estados Unidos el pasado viernes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuballama Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CubaLlama\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-18T12:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/17234840\/103741175_1778896564774891_r1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kathy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuballama\" \/>\n<meta name=\"twitter:site\" content=\"@cuballama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kathy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/\"},\"author\":{\"name\":\"Kathy\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/86cd3e3f4974437f031211213bf892d5\"},\"headline\":\"Joven padre cubano muere en accidente de tr\u00e1nsito en EE.UU.\",\"datePublished\":\"2026-05-18T12:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/\"},\"wordCount\":378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/17234840\\\/103741175_1778896564774891_r1.jpg\",\"keywords\":[\"Camionero cubano\",\"cubano en Estados Unidos\",\"cubano fallecido\",\"destacado\"],\"articleSection\":[\"Noticias\",\"USA\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/\",\"name\":\"Joven padre cubano muere en accidente de tr\u00e1nsito en EE.UU. - Cuballama Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/17234840\\\/103741175_1778896564774891_r1.jpg\",\"datePublished\":\"2026-05-18T12:00:00+00:00\",\"description\":\"Un joven padre cubano perdi\u00f3 la vida en un tr\u00e1gico accidente de tr\u00e1nsito en Estados Unidos el pasado viernes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/17234840\\\/103741175_1778896564774891_r1.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/17234840\\\/103741175_1778896564774891_r1.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Julio C\u00e9sar Est\u00e9vez. Foto: GoFundMe.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joven padre cubano muere en accidente de tr\u00e1nsito en EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"name\":\"Cuballama Noticias\",\"description\":\"Medio digital sobre Cuba y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\",\"name\":\"Cuballama\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"width\":600,\"height\":133,\"caption\":\"Cuballama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CubaLlama\",\"https:\\\/\\\/x.com\\\/cuballama\",\"https:\\\/\\\/www.instagram.com\\\/stories\\\/cuballama_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKkFE-d_axENGZcrc4as0IA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/86cd3e3f4974437f031211213bf892d5\",\"name\":\"Kathy\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/author\\\/kathy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joven padre cubano muere en accidente de tr\u00e1nsito en EE.UU. - Cuballama Noticias","description":"Un joven padre cubano perdi\u00f3 la vida en un tr\u00e1gico accidente de tr\u00e1nsito en Estados Unidos el pasado viernes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/","og_locale":"es_ES","og_type":"article","og_title":"Joven padre cubano muere en accidente de tr\u00e1nsito en EE.UU. - Cuballama Noticias","og_description":"Un joven padre cubano perdi\u00f3 la vida en un tr\u00e1gico accidente de tr\u00e1nsito en Estados Unidos el pasado viernes.","og_url":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/","og_site_name":"Cuballama Noticias","article_publisher":"https:\/\/www.facebook.com\/CubaLlama","article_published_time":"2026-05-18T12:00:00+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/17234840\/103741175_1778896564774891_r1.jpg","type":"image\/jpeg"}],"author":"Kathy","twitter_card":"summary_large_image","twitter_creator":"@cuballama","twitter_site":"@cuballama","twitter_misc":{"Escrito por":"Kathy","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/#article","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/"},"author":{"name":"Kathy","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/86cd3e3f4974437f031211213bf892d5"},"headline":"Joven padre cubano muere en accidente de tr\u00e1nsito en EE.UU.","datePublished":"2026-05-18T12:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/"},"wordCount":378,"commentCount":0,"publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/17234840\/103741175_1778896564774891_r1.jpg","keywords":["Camionero cubano","cubano en Estados Unidos","cubano fallecido","destacado"],"articleSection":["Noticias","USA"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/","url":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/","name":"Joven padre cubano muere en accidente de tr\u00e1nsito en EE.UU. - Cuballama Noticias","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/#primaryimage"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/17234840\/103741175_1778896564774891_r1.jpg","datePublished":"2026-05-18T12:00:00+00:00","description":"Un joven padre cubano perdi\u00f3 la vida en un tr\u00e1gico accidente de tr\u00e1nsito en Estados Unidos el pasado viernes.","breadcrumb":{"@id":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/#primaryimage","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/17234840\/103741175_1778896564774891_r1.jpg","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/05\/17234840\/103741175_1778896564774891_r1.jpg","width":1200,"height":630,"caption":"Julio C\u00e9sar Est\u00e9vez. Foto: GoFundMe."},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuballama.com\/noticias\/joven-padre-cubano-muere-en-accidente-de-transito-en-ee-uu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cuballama.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Joven padre cubano muere en accidente de tr\u00e1nsito en EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/www.cuballama.com\/noticias\/#website","url":"https:\/\/www.cuballama.com\/noticias\/","name":"Cuballama Noticias","description":"Medio digital sobre Cuba y el mundo","publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuballama.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cuballama.com\/noticias\/#organization","name":"Cuballama","url":"https:\/\/www.cuballama.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","width":600,"height":133,"caption":"Cuballama"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CubaLlama","https:\/\/x.com\/cuballama","https:\/\/www.instagram.com\/stories\/cuballama_oficial\/","https:\/\/www.youtube.com\/channel\/UCKkFE-d_axENGZcrc4as0IA"]},{"@type":"Person","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/86cd3e3f4974437f031211213bf892d5","name":"Kathy","url":"https:\/\/www.cuballama.com\/noticias\/author\/kathy\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/244755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/comments?post=244755"}],"version-history":[{"count":7,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/244755\/revisions"}],"predecessor-version":[{"id":244788,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/244755\/revisions\/244788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media\/244756"}],"wp:attachment":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media?parent=244755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/categories?post=244755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/tags?post=244755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}