{"id":231349,"date":"2026-01-08T12:49:51","date_gmt":"2026-01-08T17:49:51","guid":{"rendered":"https:\/\/www.cuballama.com\/noticias\/?p=231349"},"modified":"2026-01-08T12:49:54","modified_gmt":"2026-01-08T17:49:54","slug":"venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos","status":"publish","type":"post","link":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/","title":{"rendered":"Venezuela ordena liberaci\u00f3n de \u00abun n\u00famero importante\u00bb de presos pol\u00edticos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente de la Asamblea Nacional y hermano de la presidenta interina Delcy Rodr\u00edguez, Jorge Rodr\u00edguez, anunci\u00f3 este jueves la liberaci\u00f3n inmediata de \u00abun n\u00famero importante de personas detenidas\u00bb, incluyendo tanto venezolanos como extranjeros, sin confirmar cifras exactas de las personas excarceladas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante una conferencia de prensa en el parlamento, Rodr\u00edguez asegur\u00f3 que la medida busca \u201cconsolidar la paz y la convivencia pac\u00edfica\u201d en el pa\u00eds y que los procesos de excarcelaci\u00f3n \u00abya se est\u00e1n ejecutando desde este mismo momento\u00bb, con participaci\u00f3n de diversas instituciones del Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El anuncio llega en un contexto de creciente atenci\u00f3n internacional sobre la situaci\u00f3n de los derechos humanos en Venezuela, donde la oposici\u00f3n y organizaciones civiles han denunciado la existencia de presos por razones pol\u00edticas durante los \u00faltimos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta el momento, no se ha precisado si los liberados contar\u00e1n con libertad plena o estar\u00e1n sujetos a medidas cautelares. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diversas organizaciones internacionales sit\u00faan en 863 el n\u00famero de presos pol\u00edticos por el chavismo en carceles por todo el pa\u00eds. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abAl 29 de diciembre de 2025, hab\u00eda\u00a0863 presos pol\u00edticos\u00a0en\u00a0Venezuela. De ellos, 755 son hombres, 106 Mujeres y 1 adolescente; 687 son civiles y 176 Militares.\u00a0Otro grupo considerable es el de los extranjeros, en el cual hay 86 secuestrados. Los m\u00e1s reconocidos entre ellos son\u00a0Nahuel Gallo\u00a0(Argentina),\u00a0Roc\u00edo San Miguel\u00a0(Espa\u00f1a) y\u00a0Alberto Trentini\u00a0(Italia), entre otros, dijo Infobae citando reportes de la organizaci\u00f3n no gubernamental venezolana Foro Penal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEntre los venezolanos de mayor renombre figuran:\u00a0Emirlendris Ben\u00edtez, quien al momento de su cautiverio estaba embarazada y producto de las torturas abort\u00f3;\u00a0<a href=\"https:\/\/www.infobae.com\/america\/america-latina\/2025\/08\/26\/la-ong-sumate-denuncio-que-la-activista-nelida-sanchez-cumplio-un-ano-de-prision-sin-garantias-judiciales\/\" target=\"_blank\" rel=\"noreferrer noopener\">N\u00e9lida S\u00e1nchez, defensora de derechos humanos<\/a>. Fue quien form\u00f3 a los fiscales electorales para defender los votos en 2024 y lograr demostrar la derrota de\u00a0Maduro.\u00a0Enrique M\u00e1rquez, excandidato presidencial de la izquierda disidente.\u00a0Mar\u00eda Oropeza, importante dirigente de\u00a0<em>Vente Venezuela<\/em>que transmiti\u00f3 en vivo su detenci\u00f3n.\u00a0Freddy Superlano, cuyo video al momento de su secuestro dio la vuelta al mundo\u00bb; a\u00f1adi\u00f3 la publicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Asamblea Nacional y hermano de la presidenta interina Delcy Rodr\u00edguez, Jorge Rodr\u00edguez, anunci\u00f3 este jueves la liberaci\u00f3n inmediata de \u00abun n\u00famero importante de personas detenidas\u00bb, incluyendo tanto venezolanos como extranjeros, sin confirmar cifras exactas de las personas excarceladas Durante una conferencia de prensa en el parlamento, Rodr\u00edguez asegur\u00f3 que la medida [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":230613,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[957],"tags":[11,92,941,24865,11373,1030],"class_list":["post-231349","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-internacionales","tag-cuba","tag-cubanos","tag-destacado","tag-presos-de-conciencia","tag-presos-politicos","tag-venezuela"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Venezuela ordena liberaci\u00f3n de &quot;un n\u00famero importante&quot; de presos pol\u00edticos - Cuballama Noticias<\/title>\n<meta name=\"description\" content=\"Jorge Rodr\u00edguez, anunci\u00f3 este jueves la liberaci\u00f3n inmediata de &quot;un n\u00famero importante de personas detenidas&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezuela ordena liberaci\u00f3n de &quot;un n\u00famero importante&quot; de presos pol\u00edticos - Cuballama Noticias\" \/>\n<meta property=\"og:description\" content=\"Jorge Rodr\u00edguez, anunci\u00f3 este jueves la liberaci\u00f3n inmediata de &quot;un n\u00famero importante de personas detenidas&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuballama Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CubaLlama\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-08T17:49:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-08T17:49:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/04125626\/GTHP-8EXoAAS9tV.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Manu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuballama\" \/>\n<meta name=\"twitter:site\" content=\"@cuballama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/\"},\"author\":{\"name\":\"Manu\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/5889f7d070564f8386e7944d14d436cd\"},\"headline\":\"Venezuela ordena liberaci\u00f3n de \u00abun n\u00famero importante\u00bb de presos pol\u00edticos\",\"datePublished\":\"2026-01-08T17:49:51+00:00\",\"dateModified\":\"2026-01-08T17:49:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/\"},\"wordCount\":361,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04125626\\\/GTHP-8EXoAAS9tV.jpeg\",\"keywords\":[\"Cuba\",\"cubanos\",\"destacado\",\"presos de conciencia\",\"presos pol\u00edticos\",\"venezuela\"],\"articleSection\":[\"Noticias Internacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/\",\"name\":\"Venezuela ordena liberaci\u00f3n de \\\"un n\u00famero importante\\\" de presos pol\u00edticos - Cuballama Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04125626\\\/GTHP-8EXoAAS9tV.jpeg\",\"datePublished\":\"2026-01-08T17:49:51+00:00\",\"dateModified\":\"2026-01-08T17:49:54+00:00\",\"description\":\"Jorge Rodr\u00edguez, anunci\u00f3 este jueves la liberaci\u00f3n inmediata de \\\"un n\u00famero importante de personas detenidas\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04125626\\\/GTHP-8EXoAAS9tV.jpeg\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04125626\\\/GTHP-8EXoAAS9tV.jpeg\",\"width\":2048,\"height\":1366,\"caption\":\"Foto: Delcy Rodr\u00edguez\\\/ Twitter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venezuela ordena liberaci\u00f3n de \u00abun n\u00famero importante\u00bb de presos pol\u00edticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"name\":\"Cuballama Noticias\",\"description\":\"Medio digital sobre Cuba y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\",\"name\":\"Cuballama\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"width\":600,\"height\":133,\"caption\":\"Cuballama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CubaLlama\",\"https:\\\/\\\/x.com\\\/cuballama\",\"https:\\\/\\\/www.instagram.com\\\/stories\\\/cuballama_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKkFE-d_axENGZcrc4as0IA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/5889f7d070564f8386e7944d14d436cd\",\"name\":\"Manu\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/author\\\/manu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venezuela ordena liberaci\u00f3n de \"un n\u00famero importante\" de presos pol\u00edticos - Cuballama Noticias","description":"Jorge Rodr\u00edguez, anunci\u00f3 este jueves la liberaci\u00f3n inmediata de \"un n\u00famero importante de personas detenidas\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/","og_locale":"es_ES","og_type":"article","og_title":"Venezuela ordena liberaci\u00f3n de \"un n\u00famero importante\" de presos pol\u00edticos - Cuballama Noticias","og_description":"Jorge Rodr\u00edguez, anunci\u00f3 este jueves la liberaci\u00f3n inmediata de \"un n\u00famero importante de personas detenidas\"","og_url":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/","og_site_name":"Cuballama Noticias","article_publisher":"https:\/\/www.facebook.com\/CubaLlama","article_published_time":"2026-01-08T17:49:51+00:00","article_modified_time":"2026-01-08T17:49:54+00:00","og_image":[{"width":2048,"height":1366,"url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/04125626\/GTHP-8EXoAAS9tV.jpeg","type":"image\/jpeg"}],"author":"Manu","twitter_card":"summary_large_image","twitter_creator":"@cuballama","twitter_site":"@cuballama","twitter_misc":{"Escrito por":"Manu","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/#article","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/"},"author":{"name":"Manu","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/5889f7d070564f8386e7944d14d436cd"},"headline":"Venezuela ordena liberaci\u00f3n de \u00abun n\u00famero importante\u00bb de presos pol\u00edticos","datePublished":"2026-01-08T17:49:51+00:00","dateModified":"2026-01-08T17:49:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/"},"wordCount":361,"commentCount":0,"publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/04125626\/GTHP-8EXoAAS9tV.jpeg","keywords":["Cuba","cubanos","destacado","presos de conciencia","presos pol\u00edticos","venezuela"],"articleSection":["Noticias Internacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/","url":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/","name":"Venezuela ordena liberaci\u00f3n de \"un n\u00famero importante\" de presos pol\u00edticos - Cuballama Noticias","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/#primaryimage"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/04125626\/GTHP-8EXoAAS9tV.jpeg","datePublished":"2026-01-08T17:49:51+00:00","dateModified":"2026-01-08T17:49:54+00:00","description":"Jorge Rodr\u00edguez, anunci\u00f3 este jueves la liberaci\u00f3n inmediata de \"un n\u00famero importante de personas detenidas\"","breadcrumb":{"@id":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/#primaryimage","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/04125626\/GTHP-8EXoAAS9tV.jpeg","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/04125626\/GTHP-8EXoAAS9tV.jpeg","width":2048,"height":1366,"caption":"Foto: Delcy Rodr\u00edguez\/ Twitter"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuballama.com\/noticias\/venezuela-ordena-liberacion-de-un-numero-importante-de-presos-politicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cuballama.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Venezuela ordena liberaci\u00f3n de \u00abun n\u00famero importante\u00bb de presos pol\u00edticos"}]},{"@type":"WebSite","@id":"https:\/\/www.cuballama.com\/noticias\/#website","url":"https:\/\/www.cuballama.com\/noticias\/","name":"Cuballama Noticias","description":"Medio digital sobre Cuba y el mundo","publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuballama.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cuballama.com\/noticias\/#organization","name":"Cuballama","url":"https:\/\/www.cuballama.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","width":600,"height":133,"caption":"Cuballama"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CubaLlama","https:\/\/x.com\/cuballama","https:\/\/www.instagram.com\/stories\/cuballama_oficial\/","https:\/\/www.youtube.com\/channel\/UCKkFE-d_axENGZcrc4as0IA"]},{"@type":"Person","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/5889f7d070564f8386e7944d14d436cd","name":"Manu","url":"https:\/\/www.cuballama.com\/noticias\/author\/manu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/231349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/comments?post=231349"}],"version-history":[{"count":1,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/231349\/revisions"}],"predecessor-version":[{"id":231350,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/231349\/revisions\/231350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media\/230613"}],"wp:attachment":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media?parent=231349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/categories?post=231349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/tags?post=231349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}