{"id":230933,"date":"2026-01-05T21:30:49","date_gmt":"2026-01-06T02:30:49","guid":{"rendered":"https:\/\/www.cuballama.com\/noticias\/?p=230933"},"modified":"2026-01-06T13:16:58","modified_gmt":"2026-01-06T18:16:58","slug":"reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela","status":"publish","type":"post","link":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/","title":{"rendered":"Reportan r\u00e1fagas de disparos cerca del palacio presidencial de Venezuela"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">R\u00e1fagas de disparos se escucharon sobre las ocho de la noche de este lunes 5 de enero de 2026 en los alrededores del Palacio de Miraflores, la sede de la Presidencia de Venezuela, seg\u00fan dijeron distintos a testigos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta el momento no ha habido un pronunciamiento oficial sobre el hecho, informaron <em>Efe<\/em> y <em>AFP <\/em>si bien es algo que ha hecho evidente el clima de inestabilidad que se vive en la capital venezolana.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/%C3%9ALTIMAHORA?src=hash&amp;ref_src=twsrc%5Etfw\">#\u00daLTIMAHORA<\/a> | Venezuela est\u00e1 &quot;en tranquilidad&quot; tras tiros cerca a la sede presidencial seg\u00fan una fuente informada. <a href=\"https:\/\/t.co\/V3nndQvspD\">pic.twitter.com\/V3nndQvspD<\/a><\/p>&mdash; EFE Noticias (@EFEnoticias) <a href=\"https:\/\/twitter.com\/EFEnoticias\/status\/2008362316736209255?ref_src=twsrc%5Etfw\">January 6, 2026<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">Venezuela est\u00e1 \u201cen tranquilidad\u201d tras tiros cerca a la sede presidencial, seg\u00fan apunt\u00f3 una fuente informada citada por <em>Efe <\/em>pasadas las nueve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan reportaron dichas agencias, drones no identificados sobrevolaron el centro de Caracas, tras lo que se oyeron tiros de fuerzas de seguridad en respuesta.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">La periodista <a href=\"https:\/\/twitter.com\/ErikaOSanoja?ref_src=twsrc%5Etfw\">@ErikaOSanoja<\/a> escribe en Instagram que los disparos en el centro de Caracas esta noche fueron contra un drone comercial que sobrevol\u00f3 las cercan\u00edas al Palacio de Miraflores sin autorizaci\u00f3n, activ\u00e1ndose las respuestas de las fuerzas de seguridad del estado <a href=\"https:\/\/t.co\/Mz8SqVZKaD\">pic.twitter.com\/Mz8SqVZKaD<\/a><\/p>&mdash; Luigino Bracci Roa (@lubrio) <a href=\"https:\/\/twitter.com\/lubrio\/status\/2008348431664677356?ref_src=twsrc%5Etfw\">January 6, 2026<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">En redes sociales circularon de inmediato videos en lo que se escuchan los disparos, mientras que testigos dijeron a <em>Efe<\/em> que en los alrededores se o\u00eda el paso de numerosos motoristas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Preliminarmente se especul\u00f3 que podr\u00eda haberse tratado de un enfrentamiento interno, entre fuerzas del gobierno y de la oposici\u00f3n, o incluso de un \u201cgolpe de Estado\u201d.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=476&#038;href=https%3A%2F%2Fwww.facebook.com%2Freel%2F760089427121577%2F&#038;show_text=true&#038;width=267&#038;t=0\" width=\"267\" height=\"591\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\" allowFullScreen=\"true\"><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con lo que confirm\u00f3 <em>Noticias Caracol<\/em> se trat\u00f3 de un intento por repeler drones que sobrevolaron el \u00e1rea y, seg\u00fan una fuente cercana al gobierno, la situaci\u00f3n est\u00e1 controlada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSonaba como detonaciones, eran muy seguidas\u201d, dijo a <em>AFP<\/em> un vecino que vive a cinco cuadras de Miraflores. \u201cLo primero que se me vino a la mente fue ver si hab\u00eda aviones sobrevolando, pero no\u201d.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">Videos: r\u00e1fagas de disparos en los alrededores del palacio presidencial de Venezuela<a href=\"https:\/\/t.co\/8nF21YPPjT\">https:\/\/t.co\/8nF21YPPjT<\/a><\/p>&mdash; Noticias Caracol (@NoticiasCaracol) <a href=\"https:\/\/twitter.com\/NoticiasCaracol\/status\/2008354456824361214?ref_src=twsrc%5Etfw\">January 6, 2026<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script> \n\n\n\n<p class=\"wp-block-paragraph\">\u201cSolo vi dos luces rojas en el cielo\u201d, a\u00f1adi\u00f3 bajo condici\u00f3n de anonimato. \u201cDur\u00f3 aproximadamente un minuto\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ministerio de Comunicaci\u00f3n no respondi\u00f3 a\u00fan a los llamados de <em>AFP<\/em> para confirmar el hecho, pero videos a los que pudo acceder muestran el palacio presidencial a oscuras y se ve lo que parecen ser proyectiles trazadores.\u00a0<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">La periodista <a href=\"https:\/\/twitter.com\/ErikaOSanoja?ref_src=twsrc%5Etfw\">@ErikaOSanoja<\/a> escribe en Instagram que los disparos en el centro de Caracas esta noche fueron contra un drone comercial que sobrevol\u00f3 las cercan\u00edas al Palacio de Miraflores sin autorizaci\u00f3n, activ\u00e1ndose las respuestas de las fuerzas de seguridad del estado <a href=\"https:\/\/t.co\/Mz8SqVZKaD\">pic.twitter.com\/Mz8SqVZKaD<\/a><\/p>&mdash; Luigino Bracci Roa (@lubrio) <a href=\"https:\/\/twitter.com\/lubrio\/status\/2008348431664677356?ref_src=twsrc%5Etfw\">January 6, 2026<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">En las im\u00e1genes viralizadas en redes sociales pueden verse agentes de la polic\u00eda cerca de Miraflores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El incidente tuvo lugar horas despu\u00e9s de que la chavista Delcy Rodr\u00edguez jurara como presidenta encargada del pa\u00eds tras la captura del expresidente Nicol\u00e1s Maduro y su esposa, Cilia Flores, durante <a href=\"https:\/\/www.cuballama.com\/noticias\/trump-revela-detalles-sobre-la-captura-de-maduro-no-llego-a-entrar-al-bunker\/\" target=\"_blank\" rel=\"noreferrer noopener\">una operaci\u00f3n militar estadounidense<\/a> en Caracas y tres estados vecinos el pasado s\u00e1bado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan un reporte preliminar se trat\u00f3 de un intento por repeler drones que sobrevolaron el \u00e1rea.<\/p>\n","protected":false},"author":30,"featured_media":230936,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,955],"tags":[2819,941,878,29405,11576,29865,29866],"class_list":["post-230933","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-de-cuba","tag-caracas","tag-destacado","tag-disparos","tag-gobierno-venezolano","tag-nicolas-maduro-2","tag-palacio-de-miraflores","tag-tension-en-venezuela"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reportan r\u00e1fagas de disparos cerca del palacio presidencial de Venezuela - Cuballama Noticias<\/title>\n<meta name=\"description\" content=\"R\u00e1fagas de disparos se escucharon la noche de este lunes 5 de enero cerca del Palacio de Miraflores, la sede de la Presidencia de Venezuela.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reportan r\u00e1fagas de disparos cerca del palacio presidencial de Venezuela - Cuballama Noticias\" \/>\n<meta property=\"og:description\" content=\"R\u00e1fagas de disparos se escucharon la noche de este lunes 5 de enero cerca del Palacio de Miraflores, la sede de la Presidencia de Venezuela.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuballama Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CubaLlama\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-06T02:30:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T18:16:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/05212621\/Square-black-four-4x418-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kathy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuballama\" \/>\n<meta name=\"twitter:site\" content=\"@cuballama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kathy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/\"},\"author\":{\"name\":\"Kathy\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/86cd3e3f4974437f031211213bf892d5\"},\"headline\":\"Reportan r\u00e1fagas de disparos cerca del palacio presidencial de Venezuela\",\"datePublished\":\"2026-01-06T02:30:49+00:00\",\"dateModified\":\"2026-01-06T18:16:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/\"},\"wordCount\":550,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05212621\\\/Square-black-four-4x418-1.jpg\",\"keywords\":[\"Caracas\",\"destacado\",\"Disparos\",\"gobierno venezolano\",\"Nicol\u00e1s Maduro\",\"Palacio de Miraflores\",\"tensi\u00f3n en Venezuela\"],\"articleSection\":[\"Noticias\",\"Noticias de Cuba\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/\",\"name\":\"Reportan r\u00e1fagas de disparos cerca del palacio presidencial de Venezuela - Cuballama Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05212621\\\/Square-black-four-4x418-1.jpg\",\"datePublished\":\"2026-01-06T02:30:49+00:00\",\"dateModified\":\"2026-01-06T18:16:58+00:00\",\"description\":\"R\u00e1fagas de disparos se escucharon la noche de este lunes 5 de enero cerca del Palacio de Miraflores, la sede de la Presidencia de Venezuela.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05212621\\\/Square-black-four-4x418-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05212621\\\/Square-black-four-4x418-1.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Videos del momento en el que se escuchan las r\u00e1fagas de disparos en Caracas, Venezuela. Foto: X\\\/Noticias Caracol.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reportan r\u00e1fagas de disparos cerca del palacio presidencial de Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"name\":\"Cuballama Noticias\",\"description\":\"Medio digital sobre Cuba y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\",\"name\":\"Cuballama\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"width\":600,\"height\":133,\"caption\":\"Cuballama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CubaLlama\",\"https:\\\/\\\/x.com\\\/cuballama\",\"https:\\\/\\\/www.instagram.com\\\/stories\\\/cuballama_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKkFE-d_axENGZcrc4as0IA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/86cd3e3f4974437f031211213bf892d5\",\"name\":\"Kathy\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/author\\\/kathy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reportan r\u00e1fagas de disparos cerca del palacio presidencial de Venezuela - Cuballama Noticias","description":"R\u00e1fagas de disparos se escucharon la noche de este lunes 5 de enero cerca del Palacio de Miraflores, la sede de la Presidencia de Venezuela.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/","og_locale":"es_ES","og_type":"article","og_title":"Reportan r\u00e1fagas de disparos cerca del palacio presidencial de Venezuela - Cuballama Noticias","og_description":"R\u00e1fagas de disparos se escucharon la noche de este lunes 5 de enero cerca del Palacio de Miraflores, la sede de la Presidencia de Venezuela.","og_url":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/","og_site_name":"Cuballama Noticias","article_publisher":"https:\/\/www.facebook.com\/CubaLlama","article_published_time":"2026-01-06T02:30:49+00:00","article_modified_time":"2026-01-06T18:16:58+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/05212621\/Square-black-four-4x418-1.jpg","type":"image\/jpeg"}],"author":"Kathy","twitter_card":"summary_large_image","twitter_creator":"@cuballama","twitter_site":"@cuballama","twitter_misc":{"Escrito por":"Kathy","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/#article","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/"},"author":{"name":"Kathy","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/86cd3e3f4974437f031211213bf892d5"},"headline":"Reportan r\u00e1fagas de disparos cerca del palacio presidencial de Venezuela","datePublished":"2026-01-06T02:30:49+00:00","dateModified":"2026-01-06T18:16:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/"},"wordCount":550,"commentCount":0,"publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/05212621\/Square-black-four-4x418-1.jpg","keywords":["Caracas","destacado","Disparos","gobierno venezolano","Nicol\u00e1s Maduro","Palacio de Miraflores","tensi\u00f3n en Venezuela"],"articleSection":["Noticias","Noticias de Cuba"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/","url":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/","name":"Reportan r\u00e1fagas de disparos cerca del palacio presidencial de Venezuela - Cuballama Noticias","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/#primaryimage"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/05212621\/Square-black-four-4x418-1.jpg","datePublished":"2026-01-06T02:30:49+00:00","dateModified":"2026-01-06T18:16:58+00:00","description":"R\u00e1fagas de disparos se escucharon la noche de este lunes 5 de enero cerca del Palacio de Miraflores, la sede de la Presidencia de Venezuela.","breadcrumb":{"@id":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/#primaryimage","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/05212621\/Square-black-four-4x418-1.jpg","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2026\/01\/05212621\/Square-black-four-4x418-1.jpg","width":1200,"height":630,"caption":"Videos del momento en el que se escuchan las r\u00e1fagas de disparos en Caracas, Venezuela. Foto: X\/Noticias Caracol."},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuballama.com\/noticias\/reportan-rafagas-de-disparos-cerca-del-palacio-presidencial-de-venezuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cuballama.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Reportan r\u00e1fagas de disparos cerca del palacio presidencial de Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/www.cuballama.com\/noticias\/#website","url":"https:\/\/www.cuballama.com\/noticias\/","name":"Cuballama Noticias","description":"Medio digital sobre Cuba y el mundo","publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuballama.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cuballama.com\/noticias\/#organization","name":"Cuballama","url":"https:\/\/www.cuballama.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","width":600,"height":133,"caption":"Cuballama"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CubaLlama","https:\/\/x.com\/cuballama","https:\/\/www.instagram.com\/stories\/cuballama_oficial\/","https:\/\/www.youtube.com\/channel\/UCKkFE-d_axENGZcrc4as0IA"]},{"@type":"Person","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/86cd3e3f4974437f031211213bf892d5","name":"Kathy","url":"https:\/\/www.cuballama.com\/noticias\/author\/kathy\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/230933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/comments?post=230933"}],"version-history":[{"count":3,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/230933\/revisions"}],"predecessor-version":[{"id":230955,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/230933\/revisions\/230955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media\/230936"}],"wp:attachment":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media?parent=230933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/categories?post=230933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/tags?post=230933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}