{"id":191268,"date":"2024-12-05T09:38:23","date_gmt":"2024-12-05T14:38:23","guid":{"rendered":"https:\/\/www.cuballama.com\/noticias\/?p=191268"},"modified":"2024-12-05T09:38:26","modified_gmt":"2024-12-05T14:38:26","slug":"cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru","status":"publish","type":"post","link":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/","title":{"rendered":"Cubadebate se olvida de Manuel Anido, y se enfoca en la poca experiencia diplom\u00e1tica del hijo de la presidenta de Per\u00fa"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u00bfQui\u00e9n nombr\u00f3, cu\u00e1ndo, c\u00f3mo y por qu\u00e9, a Manuel Anido Cuesta \u00abasesor de D\u00edaz-Canel? \u00bfQu\u00e9 experiencia ten\u00eda? Preguntamos a Cubadebate.<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfPor qu\u00e9 el actual Viceministro Roberto Morales Ojeda, tiene tan alto cargo si en toda su \u00e9poca de estudiante en Cienfuegos, apenas alcanzaba una nota de \u00abBueno\u00bb, en sus ex\u00e1menes?<\/h3>\n\n\n\n<p>El portal oficialista cubano Cubadebate ha hecho gala una vez m\u00e1s de ese periodismo del tejado de vidrio, al hablar de c\u00f3mo David Eduardo G\u00f3mez Boluarte, hijo de la presidenta de Per\u00fa, Dina Boluarte, fue designado como tercer secretario de la Representaci\u00f3n Permanente de Per\u00fa ante la ONU. <\/p>\n\n\n\n<p><a href=\"http:\/\/www.cubadebate.cu\/noticias\/2024\/11\/29\/el-hijo-mayor-de-la-presidenta-dina-boluarte-es-nombrado-diplomatico-del-peru-ante-la-onu-ocupara-un-cargo-en-la-onu-sin-tener-experiencia-diplomatica\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Cubadebate \u00abdenuncia\u00bb <\/a>c\u00f3mo G\u00f3mez Boluarte, graduado en 2022 de la Academia Diplom\u00e1tica del Per\u00fa Javier P\u00e9rez de Cu\u00e9llar, ingres\u00f3 al servicio diplom\u00e1tico en esa misma categor\u00eda tras completar sus estudios y la noticia, de aparente poqu\u00edsima o nula importancia solo puede entenderse dado el perenne inter\u00e9s de la prensa oficialista de Cuba en resaltar los problemas que hay en otros pa\u00edses; o los que tiene a nivel gubernamental con los gobiernos de otros pa\u00edses. <\/p>\n\n\n\n<p>En este caso, que ha generado debate incluso dentro del foro de la propia publicaci\u00f3n, el inter\u00e9s del texto estaba circunscrito a la critica de las pr\u00e1cticas conocidas como \u00abnepotismo\u00bb y \u00ababuso de influencias\u00bb en otros pa\u00edses. <\/p>\n\n\n\n<p>El art\u00edculo del medio oficialista cubano cuestiona el nombramiento del hijo de la presidenta peruana, Dina Boluarte, como diplom\u00e1tico ante la ONU sin experiencia previa; pero sin embargo, en Cuba hay tantos ejemplos recientes de este tipo, siendo nuestro pa\u00eds y nuestro r\u00e9gimen expertos en \u00abla botella\u00bb y nombrar y poner ineptos de todo tipo al frente de Departamentos, Empresas y Ministerios, tan solo por ser miembros del PCC y ex oficiales del MININT y las FAR, o incluso en ejercicio de funciones, que los comentarios de los lectores cubanos al texto publicado reflejan una conciencia y coincidencia sobre situaciones similares en Cuba, utilizando t\u00e9rminos como \u00abChipre\u00bb, \u00abCatalejo\u00bb y \u00abMe\u00f1ique del pie\u00bb para aludir a la tendencia de criticar problemas externos mientras se ignoran los internos. Estas expresiones hacen referencia a cr\u00edticas culturales sobre la hipocres\u00eda y la falta de autocr\u00edtica en la sociedad cubana.<\/p>\n\n\n\n<p><strong>Listado de comentarios dejados en la publicaci\u00f3n de Cubadebate<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El da\u00f1ino nepotismo, pr\u00e1ctica com\u00fan en algunos pa\u00edses de latinoamerica.<\/li>\n\n\n\n<li>Solo en algunos paises de Latinoamerica? Existen ejemplos mas cerca.<\/li>\n\n\n\n<li>En Per\u00fa\u2026 \u00a1\u00a1\u00bfEn serio?!!<\/li>\n\n\n\n<li>(&#8230;) Lo malo es cuando otros hijos hacen de las suyas y la prensa calla<\/li>\n\n\n\n<li>Y esta noticia qu\u00e9 significa para Cuba? Creo que hay problemas m\u00e1s importantes que tratar por la prensa cubana. Y, cuidado, que nuestro techo tambi\u00e9n es de vidrio.<\/li>\n\n\n\n<li>Yo leyendo los comentarios,me pregunto,que le interesa al cubano est\u00e1 noticia,estudio diplomacia,nos pasamos el tiempo,criticando, metiendonos en los asuntos internos de otros paises,dejen de estar criticando tanto,todo no pueden ser \u00abComo Cuba\u00bb.Dediquemonos a RESOLVER nuestros problemas que son graves,que pueden destruir a nuestra Revoluci\u00f3n.No vamos a cambiar el mundo,TAMBI\u00c9N nosotros tenemos esos problemas y nadie los critica,s\u00f3lo decimos es hijo de pap\u00e1.<\/li>\n\n\n\n<li>De vidrio y bien delgadito, para que no metemos en esos temas jejejejeje.<\/li>\n\n\n\n<li>Tengo un catalejo ,que con el la luna se ve ,marte se ve ,hasta pluton se ve ,pero el me\u00f1ique del pie ,no se me ve \u2026<\/li>\n\n\n\n<li>Nepotismo en Per\u00fa solamente?<\/li>\n\n\n\n<li>Esta noticia que nada nos aporta lo \u00fanico que consigue es visualizar a\u00fan m\u00e1s lo que nos ocurre con el me\u00f1ique del pie.Pienso luego escribo.<\/li>\n\n\n\n<li>Chiiiiipreee\u2026\u2026<\/li>\n\n\n\n<li>Es muy bueno que se publique este tipo de noticia. Eso les da pie a los cubanos para expresar lo que piensan sobre los mismos problemas, pero relacionados con nuestro pa\u00eds. Creo que en Cubadebate se hace un buen esfuerzo -excepcional pienso en la prensa cubana- por darnos participaci\u00f3n. Y a pasar de que algunas veces me molesto, porque no me publican, casi nunca protesto, sobre todo cuando veo que le publican a otros que piensan como yo. Me alegro entonces de que el mensaje de todas maneras se conozca. Tambi\u00e9n me parece que Cubadebate debe siguir ampliando las oportunidades de expresarnos a los cr\u00edticos. Los comentarios de los foristas que leemos ahora supongo que son un poco m\u00e1s liberales -por decirlo de alguna manera- que los de hace unos a\u00f1os atr\u00e1s. Y ojal\u00e1 que sigamos progresando en eso.<\/li>\n\n\n\n<li>Ay, el catalejo!!!<\/li>\n\n\n\n<li>Bueno no hay que ir tan lejos\u2026. al menos el ocupa un cargo en algo que estudio y la plaza tampoco es tan alta\u2026. Somos fan\u00e1ticos a ver la paja en el ojo ajeno<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Ay, el catalejo&#8230; Ejemplos cubanos que desmontan el texto de Cubadebate<\/strong><\/h4>\n\n\n\n<p>En Cuba, la \u00abpol\u00edtica de cuadros\u00bb es esencial para garantizar la continuidad y eficacia de la Revoluci\u00f3n. Esta pol\u00edtica se centra en la selecci\u00f3n, formaci\u00f3n y evaluaci\u00f3n de l\u00edderes en diversas esferas del Estado y el Gobierno. Seg\u00fan el Decreto-Ley No. 13\/2020, el sistema de trabajo con los cuadros y sus reservas se basa en los principios y valores del Partido Comunista de Cuba, estableciendo procesos claros para su gesti\u00f3n.<\/p>\n\n\n\n<p>En Cienfuegos, por ejemplo, se conoce que una ex funcionaria del Ministerio de Salud P\u00fablica en la provincia, se le conoc\u00eda desde su \u00e9poca de estudiante como <em>\u00abArelys Caldo e Pollo\u00bb<\/em>, por haberle pasado en vena, a una paciente, caldo de pollo para alimentarlo. La paciente falleci\u00f3, pero la desde entonces cuadro de la FEU y la UJC no respondi\u00f3 por el hecho. A\u00f1os despu\u00e9s saldr\u00eda del bajo perfil para asumir cargos de importancia dentro del Ministerio de Salud en el territorio.<\/p>\n\n\n\n<p>Otro tanto sucede con el actual Viceprimer ministro\u00a0de la Rep\u00fablica de Cuba y miembro del Bur\u00f3 Pol\u00edtico del Partido Comunista, Roberto Morales Ojeda, quien se gradu\u00f3 en Medicina con apenas unos pocos \u00ab4\u00bb, casi ning\u00fan \u00ab5\u00bb y much\u00edsimos \u00ab3\u00bb en su carrera. Arrastrando incluso algunas a extraordinaros y mundiales.<\/p>\n\n\n\n<p>A pesar de haber sido siempre un mal\u00edsimo estudiante, lleg\u00f3 a ser \u00abM\u00e1ster en Salud P\u00fablica\u00bb; fue promovido a director Municipal de Salud y en su ascenso lleg\u00f3 a ser Ministro de Salud. <\/p>\n\n\n\n<p>\u00abComo cuadro profesional del PCC dirigi\u00f3 a nivel municipal y provincial hasta ser elegido Primer Secretario del Partido en Cienfuegos. En el a\u00f1o 2018 asumi\u00f3 como Vicepresidente del Consejo de Estado y de Ministros, \u00a0en 2019 es Vice primer ministro. Diputado de la VI a la IX legislaturas, es miembro del Bur\u00f3 Pol\u00edtico desde 2016, particip\u00f3 como delegado del 5to. al 8vo. Congresos del Partido,\u00bb se puede leer en una ficha biogr\u00e1fica oficialista sobre Morales Ojeda, cuyos padres viv\u00edan a escasos dos pisos de diferencia, de quien escribe.<\/p>\n\n\n\n<p>En todo ese camino, Morales Ojeda movi\u00f3 fichas para que su hermano, de quien se conoce era peor estudiante que \u00e9l, terminara como Delegado del Ministro de Turismo en la provincia de Cienfuegos. <\/p>\n\n\n\n<p><strong>Otros ejemplos de \u00ablustr\u00edsimos cuadros con experiencia\u00bb dentro del oficialismo cubano<\/strong><\/p>\n\n\n\n<p>Un ejemplo reciente es la \u00abaparici\u00f3n de una foto del periodista Pedro J. Vel\u00e1zquez, de dudos\u00edsima reputaci\u00f3n, con un pasaporte oficial en la mano, aludiendo a haber sido enviado sabe Dios a d\u00f3nde a servirle de pala a los intereses comunicacionales del r\u00e9gimen. Un  puesto que se le ha dado al llamado \u00abNecio\u00bb, por su labor de zapa ejercida durante a\u00f1os en las redes sociales en favor del r\u00e9gimen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"762\" height=\"1024\" src=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02080034\/WhatsApp-Image-2024-12-01-at-2.16.03-PM-762x1024.jpeg\" alt=\"\" class=\"wp-image-191292\" srcset=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02080034\/WhatsApp-Image-2024-12-01-at-2.16.03-PM-762x1024.jpeg 762w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02080034\/WhatsApp-Image-2024-12-01-at-2.16.03-PM-223x300.jpeg 223w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02080034\/WhatsApp-Image-2024-12-01-at-2.16.03-PM-768x1033.jpeg 768w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02080034\/WhatsApp-Image-2024-12-01-at-2.16.03-PM-1142x1536.jpeg 1142w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02080034\/WhatsApp-Image-2024-12-01-at-2.16.03-PM-150x202.jpeg 150w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02080034\/WhatsApp-Image-2024-12-01-at-2.16.03-PM-300x403.jpeg 300w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02080034\/WhatsApp-Image-2024-12-01-at-2.16.03-PM-696x936.jpeg 696w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02080034\/WhatsApp-Image-2024-12-01-at-2.16.03-PM-1068x1436.jpeg 1068w, https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02080034\/WhatsApp-Image-2024-12-01-at-2.16.03-PM.jpeg 1523w\" sizes=\"auto, (max-width: 762px) 100vw, 762px\" \/><figcaption class=\"wp-element-caption\">\u00abEl Necio\u00bb se prepara para salir de viaje con pasaporte oficial. Sus \u00abm\u00e9ritos\u00bb como defensor a ultranza del castrismo le han garantizado el pasaporte diplom\u00e1tico.<\/figcaption><\/figure>\n\n\n\n<p>Pero del practicamente desconocido \u00abNecio\u00bb podemos pasar al chico viral del momento: Manuel Anido Cuesta, hijastro del presidente Miguel D\u00edaz-Canel.<\/p>\n\n\n\n<p>\u00bfAcaso existe ejemplo m\u00e1s \u00abcaliente\u00bb, en la pr\u00e1ctica, de esta pol\u00edtica de nepotismo y favoritismo en Cuba? <\/p>\n\n\n\n<p>Anido Cuesta, licenciado en Derecho, y del que seg\u00fan fuentes no fue para nada destacado durante sus a\u00f1os como estudiante, ha sido identificado como asesor del gobierno cubano y hasta ha acompa\u00f1ado al presidente en viajes oficiales, aunque no aparece en registros oficiales de cargos p\u00fablicos. <\/p>\n\n\n\n<p>Su presencia en delegaciones oficiales, como en visitas al Vaticano y a los Emiratos \u00c1rabes, ha suscitado cuestionamientos sobre los criterios de selecci\u00f3n de asesores en el gobierno cubano y amuchos les cabe preguntarse, \u00bfbajo qu\u00e9 criterios cay\u00f3 ah\u00ed el actual novio de la actriz Ana de Armas? <\/p>\n\n\n\n<p>Sin dudas debe tratarse de una \u00abbotella\u00bb con todas las de la ley; firmes creyentes su padrastro, su madre, Cubadebate, Randy Alonso, \u00abEl Necio\u00bb y todo el que defiende ese sistema anacr\u00f3nico que gobierna la isla caribe\u00f1a, que la implementaci\u00f3n efectiva de la pol\u00edtica de cuadros es crucial para el desarrollo y la sostenibilidad del sistema pol\u00edtico cubano.<\/p>\n\n\n\n<p>Casos como el de Anido Cuesta ponen en entredicho la transparencia y meritocracia en la selecci\u00f3n de l\u00edderes de la isla, cuando en realidad, para fortalecer la confianza p\u00fablica y asegurar la eficacia gubernamental, es fundamental que la selecci\u00f3n de estos \u00abcuadros\u00bb se aplique de manera rigurosa, evitando pr\u00e1cticas de nepotismo y garantizando que los puestos de liderazgo se asignen en funci\u00f3n de m\u00e9ritos y capacidades reales, y no por ser \u00abhijos de\u00bb o \u00abdefensores de\u00bb.<\/p>\n\n\n\n<p><strong>tal vez quieras leer: <a href=\"https:\/\/www.cuballama.com\/noticias\/sandro-castro-promete-fiesta-de-cumpleanos-cuasi-historica-y-cubanos-reaccionan\/\">Sandro Castro promete fiesta de cumplea\u00f1os cuasi hist\u00f3rica y cubanos reaccionan<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La percepci\u00f3n de nepotismo y favoritismo, ejemplificada en casos como el de Manuel Anido Cuesta, socava la credibilidad de esta pol\u00edtica y resalta la necesidad de una implementaci\u00f3n m\u00e1s transparente y equitativa.<\/p>\n","protected":false},"author":13,"featured_media":191294,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,955],"tags":[6726,20867,23033,15028,5051,8348,4479,23032],"class_list":{"0":"post-191268","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"category-noticias-de-cuba","9":"tag-botella","10":"tag-cargos","11":"tag-catalejo","12":"tag-chipre","13":"tag-cubadebate","14":"tag-dirigentes-cubanos","15":"tag-influencias","16":"tag-nepotismo"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cubadebate se olvida de Manuel Anido, y se enfoca en la poca experiencia diplom\u00e1tica del hijo de la presidenta de Per\u00fa - Cuballama Noticias<\/title>\n<meta name=\"description\" content=\"Cubadebate &quot;denuncia&quot; el nombramiento del hijo de la presidenta de Per\u00fa para un cargo en la ONU. \u00bfA Manuel Anido qui\u00e9n lo nombr\u00f3 asesor?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cubadebate se olvida de Manuel Anido, y se enfoca en la poca experiencia diplom\u00e1tica del hijo de la presidenta de Per\u00fa - Cuballama Noticias\" \/>\n<meta property=\"og:description\" content=\"Cubadebate &quot;denuncia&quot; el nombramiento del hijo de la presidenta de Per\u00fa para un cargo en la ONU. \u00bfA Manuel Anido qui\u00e9n lo nombr\u00f3 asesor?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuballama Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CubaLlama\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-05T14:38:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-05T14:38:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02082203\/Untitled-design-2024-12-02T142153.004.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberto A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuballama\" \/>\n<meta name=\"twitter:site\" content=\"@cuballama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/\"},\"author\":{\"name\":\"Roberto A.\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/a58502ed4146c8e9f83872e897c76cd2\"},\"headline\":\"Cubadebate se olvida de Manuel Anido, y se enfoca en la poca experiencia diplom\u00e1tica del hijo de la presidenta de Per\u00fa\",\"datePublished\":\"2024-12-05T14:38:23+00:00\",\"dateModified\":\"2024-12-05T14:38:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/\"},\"wordCount\":1630,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/02082203\\\/Untitled-design-2024-12-02T142153.004.jpg\",\"keywords\":[\"Botella\",\"Cargos\",\"Catalejo\",\"Chipre\",\"Cubadebate\",\"Dirigentes cubanos\",\"Influencias\",\"Nepotismo\"],\"articleSection\":[\"Noticias\",\"Noticias de Cuba\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/\",\"name\":\"Cubadebate se olvida de Manuel Anido, y se enfoca en la poca experiencia diplom\u00e1tica del hijo de la presidenta de Per\u00fa - Cuballama Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/02082203\\\/Untitled-design-2024-12-02T142153.004.jpg\",\"datePublished\":\"2024-12-05T14:38:23+00:00\",\"dateModified\":\"2024-12-05T14:38:26+00:00\",\"description\":\"Cubadebate \\\"denuncia\\\" el nombramiento del hijo de la presidenta de Per\u00fa para un cargo en la ONU. \u00bfA Manuel Anido qui\u00e9n lo nombr\u00f3 asesor?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/02082203\\\/Untitled-design-2024-12-02T142153.004.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/02082203\\\/Untitled-design-2024-12-02T142153.004.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Cubadebate critica que David Eduardo G\u00f3mez Boluarte, hijo de la presidenta de Per\u00fa, Dina Boluarte, haya sido designado como tercer secretario de la Representaci\u00f3n Permanente de Per\u00fa ante la ONU. Pero, \u00bfy a estos dos malos estudiantes, qui\u00e9n los nombr\u00f3 al cargo que tienen (o tuvieron)? \u00bfDe qu\u00e9 Nepotismo habla Cubadebate? \u00bfComo lleg\u00f3 el hermano de Roberto Morales Ojeda (a la derecha) a ser Ministro del Turismo en Cienfuegos?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cubadebate se olvida de Manuel Anido, y se enfoca en la poca experiencia diplom\u00e1tica del hijo de la presidenta de Per\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"name\":\"Cuballama Noticias\",\"description\":\"Medio digital sobre Cuba y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\",\"name\":\"Cuballama\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"width\":600,\"height\":133,\"caption\":\"Cuballama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CubaLlama\",\"https:\\\/\\\/x.com\\\/cuballama\",\"https:\\\/\\\/www.instagram.com\\\/stories\\\/cuballama_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKkFE-d_axENGZcrc4as0IA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/a58502ed4146c8e9f83872e897c76cd2\",\"name\":\"Roberto A.\",\"description\":\"Roberto A. Periodista por decisi\u00f3n propia. Interesado en cualquier tema que me apasione y cada vez m\u00e1s comprometido con la verdad y la objetividad period\u00edstica. Graduado en La Habana hace ya muchos a\u00f1os, luego de una accidentada y polvorienta b\u00fasqueda de informaci\u00f3n sobre un tema in\u00e9dito. La Tesis, por cierto, desapareci\u00f3 de la biblioteca y no se conservan copias de la misma.\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/author\\\/roberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cubadebate se olvida de Manuel Anido, y se enfoca en la poca experiencia diplom\u00e1tica del hijo de la presidenta de Per\u00fa - Cuballama Noticias","description":"Cubadebate \"denuncia\" el nombramiento del hijo de la presidenta de Per\u00fa para un cargo en la ONU. \u00bfA Manuel Anido qui\u00e9n lo nombr\u00f3 asesor?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/","og_locale":"es_ES","og_type":"article","og_title":"Cubadebate se olvida de Manuel Anido, y se enfoca en la poca experiencia diplom\u00e1tica del hijo de la presidenta de Per\u00fa - Cuballama Noticias","og_description":"Cubadebate \"denuncia\" el nombramiento del hijo de la presidenta de Per\u00fa para un cargo en la ONU. \u00bfA Manuel Anido qui\u00e9n lo nombr\u00f3 asesor?","og_url":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/","og_site_name":"Cuballama Noticias","article_publisher":"https:\/\/www.facebook.com\/CubaLlama","article_published_time":"2024-12-05T14:38:23+00:00","article_modified_time":"2024-12-05T14:38:26+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02082203\/Untitled-design-2024-12-02T142153.004.jpg","type":"image\/jpeg"}],"author":"Roberto A.","twitter_card":"summary_large_image","twitter_creator":"@cuballama","twitter_site":"@cuballama","twitter_misc":{"Escrito por":"Roberto A.","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/#article","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/"},"author":{"name":"Roberto A.","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/a58502ed4146c8e9f83872e897c76cd2"},"headline":"Cubadebate se olvida de Manuel Anido, y se enfoca en la poca experiencia diplom\u00e1tica del hijo de la presidenta de Per\u00fa","datePublished":"2024-12-05T14:38:23+00:00","dateModified":"2024-12-05T14:38:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/"},"wordCount":1630,"commentCount":0,"publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02082203\/Untitled-design-2024-12-02T142153.004.jpg","keywords":["Botella","Cargos","Catalejo","Chipre","Cubadebate","Dirigentes cubanos","Influencias","Nepotismo"],"articleSection":["Noticias","Noticias de Cuba"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/","url":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/","name":"Cubadebate se olvida de Manuel Anido, y se enfoca en la poca experiencia diplom\u00e1tica del hijo de la presidenta de Per\u00fa - Cuballama Noticias","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/#primaryimage"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02082203\/Untitled-design-2024-12-02T142153.004.jpg","datePublished":"2024-12-05T14:38:23+00:00","dateModified":"2024-12-05T14:38:26+00:00","description":"Cubadebate \"denuncia\" el nombramiento del hijo de la presidenta de Per\u00fa para un cargo en la ONU. \u00bfA Manuel Anido qui\u00e9n lo nombr\u00f3 asesor?","breadcrumb":{"@id":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/#primaryimage","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02082203\/Untitled-design-2024-12-02T142153.004.jpg","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2024\/12\/02082203\/Untitled-design-2024-12-02T142153.004.jpg","width":1200,"height":630,"caption":"Cubadebate critica que David Eduardo G\u00f3mez Boluarte, hijo de la presidenta de Per\u00fa, Dina Boluarte, haya sido designado como tercer secretario de la Representaci\u00f3n Permanente de Per\u00fa ante la ONU. Pero, \u00bfy a estos dos malos estudiantes, qui\u00e9n los nombr\u00f3 al cargo que tienen (o tuvieron)? \u00bfDe qu\u00e9 Nepotismo habla Cubadebate? \u00bfComo lleg\u00f3 el hermano de Roberto Morales Ojeda (a la derecha) a ser Ministro del Turismo en Cienfuegos?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuballama.com\/noticias\/cubadebate-se-olvida-de-manuel-anido-y-se-enfoca-en-la-poca-experiencia-diplomatica-del-hijo-de-la-presidenta-de-peru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cuballama.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Cubadebate se olvida de Manuel Anido, y se enfoca en la poca experiencia diplom\u00e1tica del hijo de la presidenta de Per\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/www.cuballama.com\/noticias\/#website","url":"https:\/\/www.cuballama.com\/noticias\/","name":"Cuballama Noticias","description":"Medio digital sobre Cuba y el mundo","publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuballama.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cuballama.com\/noticias\/#organization","name":"Cuballama","url":"https:\/\/www.cuballama.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","width":600,"height":133,"caption":"Cuballama"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CubaLlama","https:\/\/x.com\/cuballama","https:\/\/www.instagram.com\/stories\/cuballama_oficial\/","https:\/\/www.youtube.com\/channel\/UCKkFE-d_axENGZcrc4as0IA"]},{"@type":"Person","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/a58502ed4146c8e9f83872e897c76cd2","name":"Roberto A.","description":"Roberto A. Periodista por decisi\u00f3n propia. Interesado en cualquier tema que me apasione y cada vez m\u00e1s comprometido con la verdad y la objetividad period\u00edstica. Graduado en La Habana hace ya muchos a\u00f1os, luego de una accidentada y polvorienta b\u00fasqueda de informaci\u00f3n sobre un tema in\u00e9dito. La Tesis, por cierto, desapareci\u00f3 de la biblioteca y no se conservan copias de la misma.","url":"https:\/\/www.cuballama.com\/noticias\/author\/roberto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/191268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/comments?post=191268"}],"version-history":[{"count":3,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/191268\/revisions"}],"predecessor-version":[{"id":191295,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/191268\/revisions\/191295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media\/191294"}],"wp:attachment":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media?parent=191268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/categories?post=191268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/tags?post=191268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}