{"id":115845,"date":"2023-02-20T15:37:11","date_gmt":"2023-02-20T20:37:11","guid":{"rendered":"https:\/\/www.cuballama.com\/noticias\/?p=115845"},"modified":"2023-02-20T15:37:13","modified_gmt":"2023-02-20T20:37:13","slug":"otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato","status":"publish","type":"post","link":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/","title":{"rendered":"Otto Ortiz arremete contra empresa de seguro cubana por incumplir contrato"},"content":{"rendered":"\n<p>Las mejores verdades se dicen jugando, reza un viejo dicho en Cuba, pero al humorista Otto Ortiz ya no le hace gracia lo que parece \u201cun mal chiste\u201d: despu\u00e9s de varios a\u00f1os, la Empresa de Seguros Nacionales (ESEN) no le acaba de reponer su veh\u00edculo, como hab\u00edan acordado en un contrato firmado hace a\u00f1os. El popular actor, un maestro del sarcasmo, lo dijo por lo claro en su muro de Facebook.<\/p>\n\n\n\n<p>\u201cNo quiero extenderme en este escrito porque en pr\u00f3ximos d\u00edas voy a ponerle coraz\u00f3n a la publicaci\u00f3n sobre la EMPRESA DE SEGUROS NACIONALES, pero de pipi que yo, con 57 a\u00f1os en las costillas ande con una motico el\u00e9ctrica, como si fuera un adolescente, porque dicha empresa no acaba de reponerme el carro que HACE A\u00d1OS espera por la reposici\u00f3n prometida cuando, HACE A\u00d1OS, hicimos el contrato\u201d, escribi\u00f3 Otto Ortiz.<\/p>\n\n\n\n<p>Con cierta dosis de sarcasmo, y resignaci\u00f3n, el comediante remat\u00f3: \u201cY por lo que veo lo de menos son los A\u00d1OS QUE HACE, lo peor son los A\u00d1OS QUE FALTAN\u201d.<\/p>\n\n\n\n<p>La publicaci\u00f3n recibi\u00f3 m\u00faltiples expresiones de solidaridad en redes sociales, pero tambi\u00e9n alguna cr\u00edtica tra\u00edda por los pelos, como la lanzada por un usuario que le pregunt\u00f3 a Otto de qu\u00e9 se quejaba, si hab\u00eda tenido muchas oportunidades de quedarse en Miami y acogerse a diversos programas migratorios en Estados Unidos, y nunca lo hizo.<\/p>\n\n\n\n<p>\u201cYo no me quejo, yo critico, yo uso la s\u00e1tira como denuncia que es muy diferente. Y lo de quedarse o no es tema demasiado complicado para tratar de explic\u00e1rtelo\u201d, respondi\u00f3 el artista, sin extenderse, aunque de eso se encargaron otros internatutas, que cuestionaron la posici\u00f3n de dejar Cuba como soluci\u00f3n individual a todos los problemas, en lugar de quedarse y reivindicar determinados derechos.<\/p>\n\n\n\n<p>Otros comentaristas vaticinaron que la soluci\u00f3n a su problema saldr\u00eda en la Mesa Redonda, en alusi\u00f3n al hecho de que cuando alguien con cierta fama publica una protesta como afecta la imagen del gobierno, como por arte de magia surgen las soluciones. No obstante, el \u201cNene\u201d que durante a\u00f1os hizo d\u00fao con \u201cEl Titi\u201d (Anael Granados) no parece muy convencido\u2026<\/p>\n\n\n\n<p>\u201cNegativo, dir\u00e1n (en la Mesa) que se pueden importar carros hybridos a precios muy elevados, tengo amigos que ya lo han hecho. Pero del seguro, SEGURO, no dir\u00e1n nada\u201d, escribi\u00f3 el humorista.<\/p>\n\n\n\n<p>Los problemas con la ESEN no son nuevos, ni cosa de la actual crisis: desde el Per\u00edodo Especial que azot\u00f3 la econom\u00eda nacional a finales del siglo XX eran recurrentes las historias de incumplimientos, o pagos de seguro irrisorios, que no alcanzaban ni para comenzar a pagar en el mercado informal los art\u00edculos a reponer.<\/p>\n\n\n\n<p>Al respecto, la filial de la ESEN en la oriental provincia de Las Tunas reconoci\u00f3 en una nota publicada a finales de 2022 que todav\u00eda no contaba con los veh\u00edculos necesarios para efectuar la reposici\u00f3n, \u201cla cual se realizar\u00e1 cuando exista tal disponibilidad, teniendo en cuenta el escalaf\u00f3n confeccionado por la fecha de ocurrencia del siniestro\u201d. Por entonces hab\u00eda 20 casos pendientes de 2017 y 98 de 2018. De entonces ac\u00e1, ni preguntar\u2026<\/p>\n\n\n\n<p>Si por alguna raz\u00f3n el cliente no quer\u00eda comprar el veh\u00edculo propuesto, por su marca o modelo, autom\u00e1ticamente pasaba al \u00faltimo lugar del escalaf\u00f3n, tras fundamentar por escrito su rechazo.<\/p>\n\n\n\n<p>Tal dilaci\u00f3n contrasta con la prontitud en que ciertos veh\u00edculos son repuestos, seg\u00fan an\u00e9cdotas y testimonios de razonable credibilidad, sobre todo cuando el asunto beneficia o le evita un problema a personajes cercanos al poder. Y no precisamente popular\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Otto Ortiz ya no le hace gracia lo que parece \u201cun mal chiste\u201d: despu\u00e9s de varios a\u00f1os, la Empresa de Seguros Nacionales no le repone su carro.<\/p>\n","protected":false},"author":24,"featured_media":115846,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,955],"tags":[252,10867,941,9045,8481],"class_list":{"0":"post-115845","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"category-noticias-de-cuba","9":"tag-artistas-cubanos","10":"tag-crisis-en-cuba","11":"tag-destacado","12":"tag-otto-ortiz","13":"tag-seguros-de-autos"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Otto Ortiz arremete contra empresa de seguro cubana por incumplir contrato - Cuballama Noticias<\/title>\n<meta name=\"description\" content=\"Otto Ortiz ya no le hace gracia lo que parece \u201cun mal chiste\u201d: despu\u00e9s de varios a\u00f1os, la Empresa de Seguros Nacionales no le repone su carro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otto Ortiz arremete contra empresa de seguro cubana por incumplir contrato - Cuballama Noticias\" \/>\n<meta property=\"og:description\" content=\"Otto Ortiz ya no le hace gracia lo que parece \u201cun mal chiste\u201d: despu\u00e9s de varios a\u00f1os, la Empresa de Seguros Nacionales no le repone su carro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuballama Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CubaLlama\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-20T20:37:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-20T20:37:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuballama.com\/noticias\/wp-content\/uploads\/2023\/02\/Otto-Ortiz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Manu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuballama\" \/>\n<meta name=\"twitter:site\" content=\"@cuballama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/\"},\"author\":{\"name\":\"Manu\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/5889f7d070564f8386e7944d14d436cd\"},\"headline\":\"Otto Ortiz arremete contra empresa de seguro cubana por incumplir contrato\",\"datePublished\":\"2023-02-20T20:37:11+00:00\",\"dateModified\":\"2023-02-20T20:37:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/\"},\"wordCount\":635,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/20153553\\\/Otto-Ortiz.jpg\",\"keywords\":[\"Artistas cubanos\",\"Crisis en Cuba\",\"destacado\",\"Otto Ortiz\",\"Seguros de Autos\"],\"articleSection\":[\"Noticias\",\"Noticias de Cuba\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/\",\"name\":\"Otto Ortiz arremete contra empresa de seguro cubana por incumplir contrato - Cuballama Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/20153553\\\/Otto-Ortiz.jpg\",\"datePublished\":\"2023-02-20T20:37:11+00:00\",\"dateModified\":\"2023-02-20T20:37:13+00:00\",\"description\":\"Otto Ortiz ya no le hace gracia lo que parece \u201cun mal chiste\u201d: despu\u00e9s de varios a\u00f1os, la Empresa de Seguros Nacionales no le repone su carro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/20153553\\\/Otto-Ortiz.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/20153553\\\/Otto-Ortiz.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otto Ortiz arremete contra empresa de seguro cubana por incumplir contrato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"name\":\"Cuballama Noticias\",\"description\":\"Medio digital sobre Cuba y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\",\"name\":\"Cuballama\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"width\":600,\"height\":133,\"caption\":\"Cuballama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CubaLlama\",\"https:\\\/\\\/x.com\\\/cuballama\",\"https:\\\/\\\/www.instagram.com\\\/stories\\\/cuballama_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKkFE-d_axENGZcrc4as0IA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/5889f7d070564f8386e7944d14d436cd\",\"name\":\"Manu\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/author\\\/manu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Otto Ortiz arremete contra empresa de seguro cubana por incumplir contrato - Cuballama Noticias","description":"Otto Ortiz ya no le hace gracia lo que parece \u201cun mal chiste\u201d: despu\u00e9s de varios a\u00f1os, la Empresa de Seguros Nacionales no le repone su carro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/","og_locale":"es_ES","og_type":"article","og_title":"Otto Ortiz arremete contra empresa de seguro cubana por incumplir contrato - Cuballama Noticias","og_description":"Otto Ortiz ya no le hace gracia lo que parece \u201cun mal chiste\u201d: despu\u00e9s de varios a\u00f1os, la Empresa de Seguros Nacionales no le repone su carro.","og_url":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/","og_site_name":"Cuballama Noticias","article_publisher":"https:\/\/www.facebook.com\/CubaLlama","article_published_time":"2023-02-20T20:37:11+00:00","article_modified_time":"2023-02-20T20:37:13+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.cuballama.com\/noticias\/wp-content\/uploads\/2023\/02\/Otto-Ortiz.jpg","type":"image\/jpeg"}],"author":"Manu","twitter_card":"summary_large_image","twitter_creator":"@cuballama","twitter_site":"@cuballama","twitter_misc":{"Escrito por":"Manu","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/#article","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/"},"author":{"name":"Manu","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/5889f7d070564f8386e7944d14d436cd"},"headline":"Otto Ortiz arremete contra empresa de seguro cubana por incumplir contrato","datePublished":"2023-02-20T20:37:11+00:00","dateModified":"2023-02-20T20:37:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/"},"wordCount":635,"commentCount":0,"publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2023\/02\/20153553\/Otto-Ortiz.jpg","keywords":["Artistas cubanos","Crisis en Cuba","destacado","Otto Ortiz","Seguros de Autos"],"articleSection":["Noticias","Noticias de Cuba"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/","url":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/","name":"Otto Ortiz arremete contra empresa de seguro cubana por incumplir contrato - Cuballama Noticias","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/#primaryimage"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2023\/02\/20153553\/Otto-Ortiz.jpg","datePublished":"2023-02-20T20:37:11+00:00","dateModified":"2023-02-20T20:37:13+00:00","description":"Otto Ortiz ya no le hace gracia lo que parece \u201cun mal chiste\u201d: despu\u00e9s de varios a\u00f1os, la Empresa de Seguros Nacionales no le repone su carro.","breadcrumb":{"@id":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/#primaryimage","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2023\/02\/20153553\/Otto-Ortiz.jpg","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2023\/02\/20153553\/Otto-Ortiz.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuballama.com\/noticias\/otto-ortiz-arremete-contra-empresa-de-seguro-cubana-por-incumplir-contrato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cuballama.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Otto Ortiz arremete contra empresa de seguro cubana por incumplir contrato"}]},{"@type":"WebSite","@id":"https:\/\/www.cuballama.com\/noticias\/#website","url":"https:\/\/www.cuballama.com\/noticias\/","name":"Cuballama Noticias","description":"Medio digital sobre Cuba y el mundo","publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuballama.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cuballama.com\/noticias\/#organization","name":"Cuballama","url":"https:\/\/www.cuballama.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","width":600,"height":133,"caption":"Cuballama"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CubaLlama","https:\/\/x.com\/cuballama","https:\/\/www.instagram.com\/stories\/cuballama_oficial\/","https:\/\/www.youtube.com\/channel\/UCKkFE-d_axENGZcrc4as0IA"]},{"@type":"Person","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/5889f7d070564f8386e7944d14d436cd","name":"Manu","url":"https:\/\/www.cuballama.com\/noticias\/author\/manu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/115845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/comments?post=115845"}],"version-history":[{"count":1,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/115845\/revisions"}],"predecessor-version":[{"id":115847,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/115845\/revisions\/115847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media\/115846"}],"wp:attachment":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media?parent=115845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/categories?post=115845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/tags?post=115845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}