{"id":100062,"date":"2022-08-12T08:14:53","date_gmt":"2022-08-12T12:14:53","guid":{"rendered":"https:\/\/www.cuballama.com\/noticias\/?p=100062"},"modified":"2022-08-12T08:14:56","modified_gmt":"2022-08-12T12:14:56","slug":"brasil-bolsonaro-no-quiere-irse","status":"publish","type":"post","link":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/","title":{"rendered":"Brasil: Bolsonaro no quiere irse"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Jair Bolsonaro est\u00e1 cuestionando el sistema electoral de Brasil<\/h2>\n\n\n\n<p>Diversos medios desde Brasil dan cuenta que el actual presidente Jair Bolsonaro estar\u00eda preparando un plan B por si pierde en las elecciones contra Lula da Silva, previstas para efectuarse el pr\u00f3ximo 2 de octubre.<\/p>\n\n\n\n<p>Frases del presidente como \u00abSolo Dios me saca de la silla presidencial\u00bb vislumbran, dicen los medios, la estrategia de Bolsonaro. Esta es: cuestionar las elecciones.<\/p>\n\n\n\n<p>\u00abY repartir dinero p\u00fablico,\u00bb a\u00f1ade el diario El Pa\u00eds.<\/p>\n\n\n\n<p>Hace 2 semanas Bolsonaro oficializ\u00f3 su candidatura a la reelecci\u00f3n frente a un Lula que lidera las encuestas con s\u00f3lida ventaja. Las \u00faltimas encuestan arrojan que el viejo izquierdista y amigo de todos los dirigentes socialistas de la regi\u00f3n, probable cuarto integrante del team conformado por Maduro, D\u00edaz-Canel y Ortega, le lleva a Bolsonaro 18 puntos de ventaja.<\/p>\n\n\n\n<p>Hasta hace unos meses la ventaja parec\u00eda m\u00e1s s\u00f3lida a\u00fan y algunos medios hasta se\u00f1alan que ahora \u00abandan empatados\u00bb.<\/p>\n\n\n\n<p>Al menos lo describen como \u00abuna batalla\u00bb donde desde hace rato ambos se est\u00e1n tirando guantazos.<\/p>\n\n\n\n<p>Lula dijo recientemente que si gana las elecciones, tendr\u00e1 que hacer algo \u00abdiferente\u00bb porque \u00absi solo se piensa en pol\u00edtica fiscal y techo de gastos\u00bb estar\u00edan \u00abacabados\u00bb.<\/p>\n\n\n\n<p>\u00abNo nos enfrentamos a una elecci\u00f3n com\u00fan, enfrentamos a un fascista cercado de milicianos por todos lados y necesitamos derrotarlo para recuperar la democracia\u00bb, afirm\u00f3 el exgobernante, quien gobern\u00f3 Brasil desde el a\u00f1o 2003 al a\u00f1o 2010.<\/p>\n\n\n\n<p>\u00abPodr\u00eda quedarme en casa, guardarme el t\u00edtulo de mejor presidente de la historia de Brasil y vivir los \u00faltimos a\u00f1os de mi vida, pero estoy viendo un pa\u00eds siendo destruido\u00bb, <a href=\"https:\/\/www.efe.com\/efe\/espana\/mundo\/lula-llama-a-derrotar-bolsonaro-para-recuperar-la-democracia-brasilena\/10001-4854921\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">se\u00f1al\u00f3 tambi\u00e9n Lula<\/a>, y dijo que su regreso ser\u00e1 para \u00abrecuperar la democracia\u00bb brasile\u00f1a.<\/p>\n\n\n\n<p>El exmandatario Luiz In\u00e1cio Lula da Silva es el favorito para ganar las elecciones de octubre, pero pudiera ser que esto no ocurriera. El diario El Pa\u00eds dice que Bolsonaro pudiera \u00abvenezualizar\u00bb a Brasil, haciendo la comparaci\u00f3n de c\u00f3mo el izquierdista sucesor de Ch\u00e1vez lo ha movido todo en Venezuela para perpetuarse en el poder.<\/p>\n\n\n\n<p>As\u00ed lo cree tambi\u00e9n el diario El Mundo, que ha dicho que \u00abes como si estuviesen preparando un golpe para las elecciones\u00bb y menciona el hecho de que la Rep\u00fablica Federativa de Brasil presenta ante las elecciones de este 2022 un ambiente similar al de los Estados Unidos de Am\u00e9rica en el 2020, cuando Trump cuestion\u00f3 fuertemente las elecciones y sus partidarios, luego, hasta asaltaron el Capitolio de los EE.UU. para impedir que el Congreso certificase la victoria de Joe Biden.<\/p>\n\n\n\n<p>Este mi\u00e9rcoles, la Fiscal\u00eda pidi\u00f3 multar a Bolsonaro <a href=\"https:\/\/www.efe.com\/efe\/america\/politica\/la-fiscalia-pide-una-multar-a-bolsonaro-por-atacar-las-elecciones-ante-embajadores\/20000035-4865384\" target=\"_blank\" rel=\"noreferrer noopener\">por atacar las elecciones<\/a> ante embajadores, probablemente tras conocer que su rival mantiene ventaja en sondeo de cara a elecciones en Brasil. De acuerdo con la nueva encuesta telef\u00f3nica de BTG\/FSB, Lula cuenta con el 41 por ciento de la intenci\u00f3n de voto en el pa\u00eds.<\/p>\n\n\n\n<p>Brasil vivir\u00e1 de aqu\u00ed hasta octubre semanas intensas, en las que se juega el futuro de la democracia en el pa\u00eds m\u00e1s grande de Am\u00e9rica Latina, donde hasta las Fuerzas Armadas se han visto involucradas. La pasada semana el ministro de Defensa de Brasil <a href=\"https:\/\/elpais.com\/internacional\/2022-08-02\/el-ministro-de-defensa-de-brasil-pide-acceso-a-los-codigos-secretos-de-las-urnas-electronicas.html\" target=\"_blank\" rel=\"noreferrer noopener\">pidi\u00f3 acceso a los c\u00f3digos secretos de las urnas electr\u00f3nicas<\/a>, debido al cuestionamiento que Bolsonaro ha hecho del sistema.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.bbc.com\/mundo\/noticias-america-latina-62239466\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Seg\u00fan el profesor de Harvard Steven Levitsky<\/a>, el presidente de Brasil, Jair Bolsonaro, \u00abviene haciendo exactamente lo que hizo Trump: cuestionar la legitimidad de las elecciones\u00bb, sembrando dudas sobre el sistema electoral porque podr\u00eda perder las elecciones de octubre. <\/p>\n\n\n\n<p><em><a href=\"https:\/\/www.bloomberglinea.com\/2022\/08\/11\/elecciones-en-brasil-bolsonaro-y-lula-estan-empatados-en-sao-paulo-segun-encuesta\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Bloomberg <\/a><\/em>afirma que Jair Bolsonaro y Luiz In\u00e1cio Lula da Silva est\u00e1n en un empate t\u00e9cnico, pero solo en S\u00e3o Paulo, el estado m\u00e1s poblado de Brasil, mientras que France 24 agrega que en plena campa\u00f1a electoral para reconquistar Brasil, el expresidente Luiz In\u00e1cio Lula da Silva dio un golpe estrat\u00e9gico, moviendo fichas para garantizar el tan siempre codiciado voto de los evang\u00e9licos en el pa\u00eds.<\/p>\n\n\n\n<p><strong>tal vez quieras leer: <a href=\"https:\/\/www.cuballama.com\/noticias\/lula-da-silva-se-casa-con-mujer-21-anos-mas-joven\/\">Lula da Silva se casa con mujer 21 a\u00f1os m\u00e1s joven<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jair Bolsonaro cuestiona el sistema electoral de Brasil y analistas y medios consideran que se ve perdido de frente a Lula da Silva<\/p>\n","protected":false},"author":13,"featured_media":100066,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[957],"tags":[13681,274],"class_list":{"0":"post-100062","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-internacionales","8":"tag-bolsonario","9":"tag-brasil"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brasil: Bolsonaro no quiere irse - Cuballama Noticias<\/title>\n<meta name=\"description\" content=\"Jair Bolsonaro cuestiona el sistema electoral de Brasil y analistas y medios consideran que se ve perdido de frente a Lula da Silva\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brasil: Bolsonaro no quiere irse - Cuballama Noticias\" \/>\n<meta property=\"og:description\" content=\"Jair Bolsonaro cuestiona el sistema electoral de Brasil y analistas y medios consideran que se ve perdido de frente a Lula da Silva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuballama Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CubaLlama\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-12T12:14:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-12T12:14:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuballama.com\/noticias\/wp-content\/uploads\/2022\/08\/2020-03-24_Pronunciamento_do_Presidente_da_Republica_Jair_Bolsonaro_em_Rede_Nacional_de_Radio_e_Televisao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberto A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuballama\" \/>\n<meta name=\"twitter:site\" content=\"@cuballama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/\"},\"author\":{\"name\":\"Roberto A.\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/a58502ed4146c8e9f83872e897c76cd2\"},\"headline\":\"Brasil: Bolsonaro no quiere irse\",\"datePublished\":\"2022-08-12T12:14:53+00:00\",\"dateModified\":\"2022-08-12T12:14:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/\"},\"wordCount\":709,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/11124720\\\/2020-03-24_Pronunciamento_do_Presidente_da_Republica_Jair_Bolsonaro_em_Rede_Nacional_de_Radio_e_Televisao.jpg\",\"keywords\":[\"Bolsonario\",\"Brasil\"],\"articleSection\":[\"Noticias Internacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/\",\"name\":\"Brasil: Bolsonaro no quiere irse - Cuballama Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/11124720\\\/2020-03-24_Pronunciamento_do_Presidente_da_Republica_Jair_Bolsonaro_em_Rede_Nacional_de_Radio_e_Televisao.jpg\",\"datePublished\":\"2022-08-12T12:14:53+00:00\",\"dateModified\":\"2022-08-12T12:14:56+00:00\",\"description\":\"Jair Bolsonaro cuestiona el sistema electoral de Brasil y analistas y medios consideran que se ve perdido de frente a Lula da Silva\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/11124720\\\/2020-03-24_Pronunciamento_do_Presidente_da_Republica_Jair_Bolsonaro_em_Rede_Nacional_de_Radio_e_Televisao.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/11124720\\\/2020-03-24_Pronunciamento_do_Presidente_da_Republica_Jair_Bolsonaro_em_Rede_Nacional_de_Radio_e_Televisao.jpg\",\"width\":1024,\"height\":683,\"caption\":\"(Bras\u00edlia - DF, 24\\\/03\\\/2020) Pronunciamento do Presidente da Rep\u00fablica, Jair Bolsonaro em Rede Nacional de R\u00e1dio e Televis\u00e3o..Foto: Isac N\u00f3brega\\\/PR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/brasil-bolsonaro-no-quiere-irse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasil: Bolsonaro no quiere irse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"name\":\"Cuballama Noticias\",\"description\":\"Medio digital sobre Cuba y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#organization\",\"name\":\"Cuballama\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"contentUrl\":\"https:\\\/\\\/cdn1.mediawpaccore.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/28171206\\\/cbll-logo-color-sm.png\",\"width\":600,\"height\":133,\"caption\":\"Cuballama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CubaLlama\",\"https:\\\/\\\/x.com\\\/cuballama\",\"https:\\\/\\\/www.instagram.com\\\/stories\\\/cuballama_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKkFE-d_axENGZcrc4as0IA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/#\\\/schema\\\/person\\\/a58502ed4146c8e9f83872e897c76cd2\",\"name\":\"Roberto A.\",\"description\":\"Roberto A. Periodista por decisi\u00f3n propia. Interesado en cualquier tema que me apasione y cada vez m\u00e1s comprometido con la verdad y la objetividad period\u00edstica. Graduado en La Habana hace ya muchos a\u00f1os, luego de una accidentada y polvorienta b\u00fasqueda de informaci\u00f3n sobre un tema in\u00e9dito. La Tesis, por cierto, desapareci\u00f3 de la biblioteca y no se conservan copias de la misma.\",\"url\":\"https:\\\/\\\/www.cuballama.com\\\/noticias\\\/author\\\/roberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brasil: Bolsonaro no quiere irse - Cuballama Noticias","description":"Jair Bolsonaro cuestiona el sistema electoral de Brasil y analistas y medios consideran que se ve perdido de frente a Lula da Silva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/","og_locale":"es_ES","og_type":"article","og_title":"Brasil: Bolsonaro no quiere irse - Cuballama Noticias","og_description":"Jair Bolsonaro cuestiona el sistema electoral de Brasil y analistas y medios consideran que se ve perdido de frente a Lula da Silva","og_url":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/","og_site_name":"Cuballama Noticias","article_publisher":"https:\/\/www.facebook.com\/CubaLlama","article_published_time":"2022-08-12T12:14:53+00:00","article_modified_time":"2022-08-12T12:14:56+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.cuballama.com\/noticias\/wp-content\/uploads\/2022\/08\/2020-03-24_Pronunciamento_do_Presidente_da_Republica_Jair_Bolsonaro_em_Rede_Nacional_de_Radio_e_Televisao.jpg","type":"image\/jpeg"}],"author":"Roberto A.","twitter_card":"summary_large_image","twitter_creator":"@cuballama","twitter_site":"@cuballama","twitter_misc":{"Escrito por":"Roberto A.","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/#article","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/"},"author":{"name":"Roberto A.","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/a58502ed4146c8e9f83872e897c76cd2"},"headline":"Brasil: Bolsonaro no quiere irse","datePublished":"2022-08-12T12:14:53+00:00","dateModified":"2022-08-12T12:14:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/"},"wordCount":709,"commentCount":0,"publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/08\/11124720\/2020-03-24_Pronunciamento_do_Presidente_da_Republica_Jair_Bolsonaro_em_Rede_Nacional_de_Radio_e_Televisao.jpg","keywords":["Bolsonario","Brasil"],"articleSection":["Noticias Internacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/","url":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/","name":"Brasil: Bolsonaro no quiere irse - Cuballama Noticias","isPartOf":{"@id":"https:\/\/www.cuballama.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/#primaryimage"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/08\/11124720\/2020-03-24_Pronunciamento_do_Presidente_da_Republica_Jair_Bolsonaro_em_Rede_Nacional_de_Radio_e_Televisao.jpg","datePublished":"2022-08-12T12:14:53+00:00","dateModified":"2022-08-12T12:14:56+00:00","description":"Jair Bolsonaro cuestiona el sistema electoral de Brasil y analistas y medios consideran que se ve perdido de frente a Lula da Silva","breadcrumb":{"@id":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/#primaryimage","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/08\/11124720\/2020-03-24_Pronunciamento_do_Presidente_da_Republica_Jair_Bolsonaro_em_Rede_Nacional_de_Radio_e_Televisao.jpg","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2022\/08\/11124720\/2020-03-24_Pronunciamento_do_Presidente_da_Republica_Jair_Bolsonaro_em_Rede_Nacional_de_Radio_e_Televisao.jpg","width":1024,"height":683,"caption":"(Bras\u00edlia - DF, 24\/03\/2020) Pronunciamento do Presidente da Rep\u00fablica, Jair Bolsonaro em Rede Nacional de R\u00e1dio e Televis\u00e3o..Foto: Isac N\u00f3brega\/PR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuballama.com\/noticias\/brasil-bolsonaro-no-quiere-irse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cuballama.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Brasil: Bolsonaro no quiere irse"}]},{"@type":"WebSite","@id":"https:\/\/www.cuballama.com\/noticias\/#website","url":"https:\/\/www.cuballama.com\/noticias\/","name":"Cuballama Noticias","description":"Medio digital sobre Cuba y el mundo","publisher":{"@id":"https:\/\/www.cuballama.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuballama.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cuballama.com\/noticias\/#organization","name":"Cuballama","url":"https:\/\/www.cuballama.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","contentUrl":"https:\/\/cdn1.mediawpaccore.net\/wp-content\/uploads\/2021\/12\/28171206\/cbll-logo-color-sm.png","width":600,"height":133,"caption":"Cuballama"},"image":{"@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CubaLlama","https:\/\/x.com\/cuballama","https:\/\/www.instagram.com\/stories\/cuballama_oficial\/","https:\/\/www.youtube.com\/channel\/UCKkFE-d_axENGZcrc4as0IA"]},{"@type":"Person","@id":"https:\/\/www.cuballama.com\/noticias\/#\/schema\/person\/a58502ed4146c8e9f83872e897c76cd2","name":"Roberto A.","description":"Roberto A. Periodista por decisi\u00f3n propia. Interesado en cualquier tema que me apasione y cada vez m\u00e1s comprometido con la verdad y la objetividad period\u00edstica. Graduado en La Habana hace ya muchos a\u00f1os, luego de una accidentada y polvorienta b\u00fasqueda de informaci\u00f3n sobre un tema in\u00e9dito. La Tesis, por cierto, desapareci\u00f3 de la biblioteca y no se conservan copias de la misma.","url":"https:\/\/www.cuballama.com\/noticias\/author\/roberto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/100062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/comments?post=100062"}],"version-history":[{"count":4,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/100062\/revisions"}],"predecessor-version":[{"id":100094,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/posts\/100062\/revisions\/100094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media\/100066"}],"wp:attachment":[{"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/media?parent=100062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/categories?post=100062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuballama.com\/noticias\/wp-json\/wp\/v2\/tags?post=100062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}